{"id":17061,"date":"2021-12-14T15:58:21","date_gmt":"2021-12-14T15:58:21","guid":{"rendered":"https:\/\/boss2.startlingideas.com\/uncategorized-us\/rocket-space"},"modified":"2022-06-20T09:35:08","modified_gmt":"2022-06-20T09:35:08","slug":"rocket-space","status":"publish","type":"post","link":"https:\/\/ihg.bossdesign.com\/us\/projects-us\/workspace-us\/rocket-space","title":{"rendered":"Rocket Space"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"17061\" class=\"elementor elementor-17061 elementor-2468\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-37f50af0 animated-slow elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"37f50af0\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4273d89a\" data-id=\"4273d89a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2d5df219 elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"2d5df219\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Rocket Space<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-57ca1cb1 elementor-widget elementor-widget-text-editor\" data-id=\"57ca1cb1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Overview<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dbd6078 elementor-widget elementor-widget-text-editor\" data-id=\"dbd6078\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Rocket Space is a flexible, hassle-free, professional place to work from. Spaces have been created to stimulate and build a strong company culture. The managed office space allows people to focus on activities that benefit their company. It was an essential part of the brief to create multiple spaces for brainstorming, fast meetings, large group breakout and laptop working, as well as relaxation areas in the work caf\u00e9 and city garden.<\/p><p>The Trinetic task chair from Boss was chosen for each individual workstation. Whist the Arran swivel with arms was selected for hot desk spaces still providing the ergonomic support and aesthetic required.<\/p><p>Commenting on the project, Design Director, said \u201cIt was great to be able to create this space for innovative start-ups and tech businesses to thrive and develop in a space that reflects their ethos. The alignment of the workspace with the Boss portfolio made for a truly inspiring space.\u201d<\/p><p>\u201cWe knew Boss would be the perfect choice to supply high quality, aesthetically pleasing furniture which would sit extremely well within the industrial environment. The support from the Boss sales team was great as always, and they were always on hand to give us product advice.\u201d<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5a0a5aac elementor-widget elementor-widget-text-editor\" data-id=\"5a0a5aac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Arran<\/b><br>Work Chair<\/p><p><b>Trinetic<\/b><br>Task Chair<\/p><p><b>Kruze<\/b><br>Meeting &amp; Lounge Chair<\/p><p><b>Flamingo<\/b><br>Occasional Work Table<\/p><p><b>Myriad<\/b><br>Lounge Chair<\/p><p> <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8a2f01e elementor-widget elementor-widget-text-editor\" data-id=\"8a2f01e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\">Designer\/Architect<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1d83675d elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"1d83675d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/https:\/\/ihg.bossdesign.com\/projects\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Back to project gallery<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-274685ec\" data-id=\"274685ec\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-78a5053c elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"78a5053c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/05\/06213101\/RocketSpace-Case-Study-Boss-Design--1024x1024.jpg\" class=\"attachment-large size-large wp-image-15103\" alt=\"\" srcset=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/05\/06213101\/RocketSpace-Case-Study-Boss-Design--1024x1024.jpg 1024w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/05\/06213101\/RocketSpace-Case-Study-Boss-Design--300x300.jpg 300w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/05\/06213101\/RocketSpace-Case-Study-Boss-Design--150x150.jpg 150w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/05\/06213101\/RocketSpace-Case-Study-Boss-Design--768x768.jpg 768w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/05\/06213101\/RocketSpace-Case-Study-Boss-Design--32x32.jpg 32w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/05\/06213101\/RocketSpace-Case-Study-Boss-Design--600x600.jpg 600w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/05\/06213101\/RocketSpace-Case-Study-Boss-Design--100x100.jpg 100w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/05\/06213101\/RocketSpace-Case-Study-Boss-Design-.jpg 1080w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5e48a00 animated-slow elementor-invisible elementor-widget elementor-widget-image\" data-id=\"5e48a00\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"900\" src=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/05\/06213415\/RocketSpace-Case-Study-Boss-Design-6-910x1024.jpg\" class=\"attachment-large size-large wp-image-15115\" alt=\"\" srcset=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/05\/06213415\/RocketSpace-Case-Study-Boss-Design-6-910x1024.jpg 910w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/05\/06213415\/RocketSpace-Case-Study-Boss-Design-6-267x300.jpg 267w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/05\/06213415\/RocketSpace-Case-Study-Boss-Design-6-768x864.jpg 768w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/05\/06213415\/RocketSpace-Case-Study-Boss-Design-6-600x675.jpg 600w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/05\/06213415\/RocketSpace-Case-Study-Boss-Design-6.jpg 960w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dae9a7a animated-slow elementor-invisible elementor-widget elementor-widget-image\" data-id=\"dae9a7a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"900\" src=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/05\/06213409\/RocketSpace-Case-Study-Boss-Design-8-910x1024.jpg\" class=\"attachment-large size-large wp-image-15109\" alt=\"\" srcset=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/05\/06213409\/RocketSpace-Case-Study-Boss-Design-8-910x1024.jpg 910w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/05\/06213409\/RocketSpace-Case-Study-Boss-Design-8-267x300.jpg 267w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/05\/06213409\/RocketSpace-Case-Study-Boss-Design-8-768x864.jpg 768w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/05\/06213409\/RocketSpace-Case-Study-Boss-Design-8-600x675.jpg 600w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/05\/06213409\/RocketSpace-Case-Study-Boss-Design-8.jpg 960w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a55d942 animated-slow elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"a55d942\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-33f1f469\" data-id=\"33f1f469\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7a7303ce elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"7a7303ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5d162784 animated-slow elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"5d162784\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-244c26ef\" data-id=\"244c26ef\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-55c9b1f1 elementor-widget elementor-widget-heading\" data-id=\"55c9b1f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Gallery<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cdc9773 animated-slow elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"cdc9773\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-159c405f\" data-id=\"159c405f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6249bab2 elementor-widget elementor-widget-bdw_banner_slider\" data-id=\"6249bab2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"bdw_banner_slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"l-banner l-banner--slick js-carousel\">\n    <div class=\"c-carousel c-carousel__single c-carousel__single--loading js-carousel__carousel\">\n        <div>\n    <a href=\"\" aria-label=\"\" >\n        <picture>\n            <source media=\"(min-width: 980px)\" srcset=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/05\/06213421\/RocketSpace-Case-Study-Boss-Design-4.jpg\">\n            <img decoding=\"async\" src=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/05\/06213421\/RocketSpace-Case-Study-Boss-Design-4.jpg\" alt=\"\">\n        <\/picture>\n    <\/a>\n<\/div><div>\n    <a href=\"\" aria-label=\"\" >\n        <picture>\n            <source media=\"(min-width: 980px)\" srcset=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/05\/06213425\/RocketSpace-Case-Study-Boss-Design-3.jpg\">\n            <img decoding=\"async\" src=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/05\/06213425\/RocketSpace-Case-Study-Boss-Design-3.jpg\" alt=\"\">\n        <\/picture>\n    <\/a>\n<\/div><div>\n    <a href=\"\" aria-label=\"\" >\n        <picture>\n            <source media=\"(min-width: 980px)\" srcset=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/05\/06213406\/RocketSpace-Case-Study-Boss-Design-2.jpg\">\n            <img decoding=\"async\" src=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/05\/06213406\/RocketSpace-Case-Study-Boss-Design-2.jpg\" alt=\"\">\n        <\/picture>\n    <\/a>\n<\/div>    <\/div>\n    <div class=\"c-carousel__pagination js-carousel__pagination\">\n    <span class=\"js-carousel__pagination--current\">1<\/span>\/<span class=\"js-carousel__pagination--total\">3<\/span>\n<\/div>\n<ul class=\"c-carousel__controls js-carousel__controls\">\n    <li class=\"c-carousel__control c-carousel-controls c-carousel-controls__previous js-carousel__control--previous\">\n        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"9.849\" height=\"17.699\" viewBox=\"0 0 9.849 17.699\">\n    <path id=\"previous-arrow\" data-name=\"back-chevron\" d=\"M0,16.992,8.789,8.2.585,0\" transform=\"translate(9.496 17.346) rotate(180)\" fill=\"none\" stroke=\"#000\" stroke-miterlimit=\"10\" stroke-width=\"1\"\/>\n<\/svg>        <span>Previous<\/span>\n    <\/li>\n    <li class=\"c-carousel__control c-carousel-controls c-carousel-controls__next js-carousel__control--next\">\n        <span>Next<\/span>\n        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"9.849\" height=\"17.699\" viewBox=\"0 0 9.849 17.699\">\n    <path id=\"next-arrow\" data-name=\"forward-chevron\" d=\"M4777.469,1010.609l8.789-8.789-8.2-8.2\" transform=\"translate(-4777.115 -993.263)\" fill=\"none\" stroke=\"#000\" stroke-miterlimit=\"10\" stroke-width=\"1\"\/>\n<\/svg>    <\/li>\n<\/ul><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-65d6a427 animated-slow elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"65d6a427\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6ce371e3\" data-id=\"6ce371e3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-612f1882 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"612f1882\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-28696f3d animated-slow elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"28696f3d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6d91bd8f\" data-id=\"6d91bd8f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-eb4954d elementor-widget elementor-widget-heading\" data-id=\"eb4954d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Featured Products<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6e4f78f5 animated-slow elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"6e4f78f5\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1470dcc5\" data-id=\"1470dcc5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-32ed289c elementor-widget elementor-widget-bdw_product_slider\" data-id=\"32ed289c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"bdw_product_slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"l-product-slider l-product-slider--loading js-product-slides\">\n    <div class=\"js-product-slides--loading js-product-slides__carousel\">\n        <div >\n    <div\n            class=\"l-product-slide js-product-slides__slide\"\n            data-url=\"https:\/\/ihg.bossdesign.com\/us\/product\/kitt\"\n            data-media=\"https:\/\/ihg.bossdesign.com\/wp-content\/uploads\/2024\/01\/Kitt-Leading-Shot--scaled.jpg\"\n            data-description=\"Kitt\"\n            aria-expanded=\"false\">\n        \n<div data-item_id=\"54485\" data-action=\"alg-wc-wl-toggle\" class=\"alg-wc-wl-btn add alg-wc-wl-thumb-btn alg-wc-wl-thumb-btn-abs alg-wc-wl-thumb-btn-loop\">\n\t<div class=\"alg-wc-wl-view-state alg-wc-wl-view-state-add\">\n\t\t<i class=\"l-product-slide__wishlist l-product-slide__wishlist--add\" aria-hidden=\"true\"><\/i>\n\t<\/div>\n\t<div class=\"alg-wc-wl-view-state alg-wc-wl-view-state-remove\">\n\t\t<i class=\"l-product-slide__wishlist l-product-slide__wishlist--remove\" aria-hidden=\"true\"><\/i>\n\t<\/div>\n\t<\/div><a href=\"https:\/\/ihg.bossdesign.com\/us\/projects-us\/workspace-us\/rocket-space\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <div class=\"l-product-slide__image\">\n            <img decoding=\"async\" src=\"https:\/\/ihg.bossdesign.com\/wp-content\/uploads\/2024\/01\/Kitt-Leading-Shot--scaled.jpg\" alt=\"Kitt\" \/>\n        <\/div>\n        <div class=\"l-product-slide__info js-product-slides__slide-info\">\n            <div class=\"l-product-slide__info-inner\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/ihg.bossdesign.com\/wp-content\/uploads\/2024\/01\/Kitt-Leading-Shot--300x225.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Kitt\" srcset=\"https:\/\/ihg.bossdesign.com\/wp-content\/uploads\/2024\/01\/Kitt-Leading-Shot--300x225.jpg 300w, https:\/\/ihg.bossdesign.com\/wp-content\/uploads\/2024\/01\/Kitt-Leading-Shot--1024x768.jpg 1024w, https:\/\/ihg.bossdesign.com\/wp-content\/uploads\/2024\/01\/Kitt-Leading-Shot--768x576.jpg 768w, https:\/\/ihg.bossdesign.com\/wp-content\/uploads\/2024\/01\/Kitt-Leading-Shot--1536x1152.jpg 1536w, https:\/\/ihg.bossdesign.com\/wp-content\/uploads\/2024\/01\/Kitt-Leading-Shot--2048x1536.jpg 2048w, https:\/\/ihg.bossdesign.com\/wp-content\/uploads\/2024\/01\/Kitt-Leading-Shot--600x450.jpg 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>                <h5>\n                    Kitt                <\/h5>\n                \n                <div\n                        hidden=\"hidden\"\n                        class=\"l-product-slide__call-to-action js-product-slides__call-to-action\">\n                    <p>\n                        <a href=\"https:\/\/ihg.bossdesign.com\/us\/product\/kitt\">View product<\/a>\n                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"25.052\" height=\"18.745\" viewBox=\"0 0 25.052 18.745\">\n                            <g id=\"Group_157\" data-name=\"Group 157\" transform=\"translate(0 0.354)\">\n                                <g id=\"Group_75\" data-name=\"Group 75\" transform=\"translate(0 0)\">\n                                    <g id=\"Group_74\" data-name=\"Group 74\">\n                                        <line id=\"Line_40\" data-name=\"Line 40\" x2=\"24.552\" transform=\"translate(0 9.019)\" fill=\"none\" stroke=\"#000\" stroke-linejoin=\"round\" stroke-width=\"1\"\/>\n                                        <path id=\"Path_41\" data-name=\"Path 41\" d=\"M4596.461,1377.324l9.019,9.019-9.019,9.019\" transform=\"translate(-4580.928 -1377.324)\" fill=\"none\" stroke=\"#000\" stroke-linejoin=\"round\" stroke-width=\"1\"\/>\n                                    <\/g>\n                                <\/g>\n                            <\/g>\n                        <\/svg>\n                    <\/p>\n                <\/div>\n            <\/div>\n        <\/div>\n        <div hidden=\"hidden\"\n             class=\"l-product-slide__pin js-product-slides__slide-pin\">\n            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"37.863\" height=\"37.857\" viewBox=\"0 0 37.863 37.857\">\n                <path id=\"Path_53\" data-name=\"Path 53\" d=\"M4264.124,1231.55a18.982,18.982,0,0,1,32.5-13.274,18.769,18.769,0,0,1,5.362,13.274,19.121,19.121,0,0,1-18.934,18.926,18.135,18.135,0,0,1-5.32-.814,21.083,21.083,0,0,0,1.032-1.846,31.1,31.1,0,0,0,1.478-4.733q.226-.96.671-2.591a4.786,4.786,0,0,0,1.774,1.629,7.737,7.737,0,0,0,7.022-.3,11.669,11.669,0,0,0,5.323-6.875,13.977,13.977,0,0,0-.334-9.057,10.672,10.672,0,0,0-5.951-6.027,16.44,16.44,0,0,0-10.5.333,11.8,11.8,0,0,0-7.1,6.469,15.056,15.056,0,0,0-.629,3.366,15.791,15.791,0,0,0,.11,3.253,6.4,6.4,0,0,0,1.11,2.847,5.675,5.675,0,0,0,2.363,1.922.624.624,0,0,0,.594,0c.2-.1.392-.49.587-1.181a3.6,3.6,0,0,0,.224-1.4c-.047-.1-.146-.273-.293-.519a7.205,7.205,0,0,1-1.034-5.285,9.281,9.281,0,0,1,2.292-4.693,10.273,10.273,0,0,1,6.394-2.664,8.447,8.447,0,0,1,6.246,2,7.983,7.983,0,0,1,1.81,3.918,11.963,11.963,0,0,1,0,4.4,13.258,13.258,0,0,1-1.44,3.958q-1.852,2.884-4.365,2.957a3.271,3.271,0,0,1-2.4-1.147,2.576,2.576,0,0,1-.553-2.477q.148-.812.889-3.18a16.954,16.954,0,0,0,.812-3.547q-.221-2.811-2.587-2.886a3.523,3.523,0,0,0-2.738,1.663,6.648,6.648,0,0,0-.965,3.29,8.762,8.762,0,0,0,.668,2.957q-.81,3.327-1.257,5.322c-.1.344-.37,1.406-.814,3.18a23.632,23.632,0,0,0-.739,4.067v2.072a19.491,19.491,0,0,1-8.278-7.061A18.309,18.309,0,0,1,4264.124,1231.55Z\" transform=\"translate(-4264.124 -1212.619)\"\/>\n            <\/svg>\n        <\/div>\n        <\/a><a href=\"https:\/\/ihg.bossdesign.com\/us\/product\/kitt\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_54485\" data-quantity=\"1\" class=\"button product_type_variable\" data-product_id=\"54485\" data-product_sku=\"\" aria-label=\"Select options for &ldquo;Kitt&rdquo;\" rel=\"nofollow\">Read more<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_54485\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n        <a class=\"l-product-slide__link\" href=\"https:\/\/ihg.bossdesign.com\/us\/product\/kitt\"><\/a>\n    <\/div>\n<\/div><div >\n    <div\n            class=\"l-product-slide js-product-slides__slide\"\n            data-url=\"https:\/\/ihg.bossdesign.com\/us\/product\/paloma-meetingconfigure\"\n            data-media=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/05\/20131628\/Paloma-Lounge-Boss-Design-Lounge-Chair-1.jpg\"\n            data-description=\"Paloma Lounge US\"\n            aria-expanded=\"false\">\n        \n<div data-item_id=\"54012\" data-action=\"alg-wc-wl-toggle\" class=\"alg-wc-wl-btn add alg-wc-wl-thumb-btn alg-wc-wl-thumb-btn-abs alg-wc-wl-thumb-btn-loop\">\n\t<div class=\"alg-wc-wl-view-state alg-wc-wl-view-state-add\">\n\t\t<i class=\"l-product-slide__wishlist l-product-slide__wishlist--add\" aria-hidden=\"true\"><\/i>\n\t<\/div>\n\t<div class=\"alg-wc-wl-view-state alg-wc-wl-view-state-remove\">\n\t\t<i class=\"l-product-slide__wishlist l-product-slide__wishlist--remove\" aria-hidden=\"true\"><\/i>\n\t<\/div>\n\t<\/div><a href=\"https:\/\/ihg.bossdesign.com\/us\/projects-us\/workspace-us\/rocket-space\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <div class=\"l-product-slide__image\">\n            <img decoding=\"async\" src=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/05\/20131628\/Paloma-Lounge-Boss-Design-Lounge-Chair-1.jpg\" alt=\"Paloma Lounge US\" \/>\n        <\/div>\n        <div class=\"l-product-slide__info js-product-slides__slide-info\">\n            <div class=\"l-product-slide__info-inner\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/05\/20131628\/Paloma-Lounge-Boss-Design-Lounge-Chair-1-300x225.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Paloma Lounge US\" srcset=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/05\/20131628\/Paloma-Lounge-Boss-Design-Lounge-Chair-1-300x225.jpg 300w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/05\/20131628\/Paloma-Lounge-Boss-Design-Lounge-Chair-1-1024x768.jpg 1024w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/05\/20131628\/Paloma-Lounge-Boss-Design-Lounge-Chair-1-768x576.jpg 768w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/05\/20131628\/Paloma-Lounge-Boss-Design-Lounge-Chair-1-600x450.jpg 600w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/05\/20131628\/Paloma-Lounge-Boss-Design-Lounge-Chair-1.jpg 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>                <h5>\n                    Paloma Lounge US                <\/h5>\n                \n                <div\n                        hidden=\"hidden\"\n                        class=\"l-product-slide__call-to-action js-product-slides__call-to-action\">\n                    <p>\n                        <a href=\"https:\/\/ihg.bossdesign.com\/us\/product\/paloma-meetingconfigure\">View product<\/a>\n                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"25.052\" height=\"18.745\" viewBox=\"0 0 25.052 18.745\">\n                            <g id=\"Group_157\" data-name=\"Group 157\" transform=\"translate(0 0.354)\">\n                                <g id=\"Group_75\" data-name=\"Group 75\" transform=\"translate(0 0)\">\n                                    <g id=\"Group_74\" data-name=\"Group 74\">\n                                        <line id=\"Line_40\" data-name=\"Line 40\" x2=\"24.552\" transform=\"translate(0 9.019)\" fill=\"none\" stroke=\"#000\" stroke-linejoin=\"round\" stroke-width=\"1\"\/>\n                                        <path id=\"Path_41\" data-name=\"Path 41\" d=\"M4596.461,1377.324l9.019,9.019-9.019,9.019\" transform=\"translate(-4580.928 -1377.324)\" fill=\"none\" stroke=\"#000\" stroke-linejoin=\"round\" stroke-width=\"1\"\/>\n                                    <\/g>\n                                <\/g>\n                            <\/g>\n                        <\/svg>\n                    <\/p>\n                <\/div>\n            <\/div>\n        <\/div>\n        <div hidden=\"hidden\"\n             class=\"l-product-slide__pin js-product-slides__slide-pin\">\n            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"37.863\" height=\"37.857\" viewBox=\"0 0 37.863 37.857\">\n                <path id=\"Path_53\" data-name=\"Path 53\" d=\"M4264.124,1231.55a18.982,18.982,0,0,1,32.5-13.274,18.769,18.769,0,0,1,5.362,13.274,19.121,19.121,0,0,1-18.934,18.926,18.135,18.135,0,0,1-5.32-.814,21.083,21.083,0,0,0,1.032-1.846,31.1,31.1,0,0,0,1.478-4.733q.226-.96.671-2.591a4.786,4.786,0,0,0,1.774,1.629,7.737,7.737,0,0,0,7.022-.3,11.669,11.669,0,0,0,5.323-6.875,13.977,13.977,0,0,0-.334-9.057,10.672,10.672,0,0,0-5.951-6.027,16.44,16.44,0,0,0-10.5.333,11.8,11.8,0,0,0-7.1,6.469,15.056,15.056,0,0,0-.629,3.366,15.791,15.791,0,0,0,.11,3.253,6.4,6.4,0,0,0,1.11,2.847,5.675,5.675,0,0,0,2.363,1.922.624.624,0,0,0,.594,0c.2-.1.392-.49.587-1.181a3.6,3.6,0,0,0,.224-1.4c-.047-.1-.146-.273-.293-.519a7.205,7.205,0,0,1-1.034-5.285,9.281,9.281,0,0,1,2.292-4.693,10.273,10.273,0,0,1,6.394-2.664,8.447,8.447,0,0,1,6.246,2,7.983,7.983,0,0,1,1.81,3.918,11.963,11.963,0,0,1,0,4.4,13.258,13.258,0,0,1-1.44,3.958q-1.852,2.884-4.365,2.957a3.271,3.271,0,0,1-2.4-1.147,2.576,2.576,0,0,1-.553-2.477q.148-.812.889-3.18a16.954,16.954,0,0,0,.812-3.547q-.221-2.811-2.587-2.886a3.523,3.523,0,0,0-2.738,1.663,6.648,6.648,0,0,0-.965,3.29,8.762,8.762,0,0,0,.668,2.957q-.81,3.327-1.257,5.322c-.1.344-.37,1.406-.814,3.18a23.632,23.632,0,0,0-.739,4.067v2.072a19.491,19.491,0,0,1-8.278-7.061A18.309,18.309,0,0,1,4264.124,1231.55Z\" transform=\"translate(-4264.124 -1212.619)\"\/>\n            <\/svg>\n        <\/div>\n        <\/a><a href=\"https:\/\/ihg.bossdesign.com\/us\/product\/paloma-meetingconfigure\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_54012\" data-quantity=\"1\" class=\"button product_type_variable\" data-product_id=\"54012\" data-product_sku=\"\" aria-label=\"Select options for &ldquo;Paloma Lounge US&rdquo;\" rel=\"nofollow\">Select options<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_54012\" class=\"screen-reader-text\">\n\t\tThis product has multiple variants. The options may be chosen on the product page\t<\/span>\n        <a class=\"l-product-slide__link\" href=\"https:\/\/ihg.bossdesign.com\/us\/product\/paloma-meetingconfigure\"><\/a>\n    <\/div>\n<\/div><div >\n    <div\n            class=\"l-product-slide js-product-slides__slide\"\n            data-url=\"https:\/\/ihg.bossdesign.com\/us\/product\/ola-tubconfigure\"\n            data-media=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2022\/09\/17122150\/OlaTub-Boss-Design-Chair-2-.jpg\"\n            data-description=\"Ola Tub US\"\n            aria-expanded=\"false\">\n        \n<div data-item_id=\"54009\" data-action=\"alg-wc-wl-toggle\" class=\"alg-wc-wl-btn add alg-wc-wl-thumb-btn alg-wc-wl-thumb-btn-abs alg-wc-wl-thumb-btn-loop\">\n\t<div class=\"alg-wc-wl-view-state alg-wc-wl-view-state-add\">\n\t\t<i class=\"l-product-slide__wishlist l-product-slide__wishlist--add\" aria-hidden=\"true\"><\/i>\n\t<\/div>\n\t<div class=\"alg-wc-wl-view-state alg-wc-wl-view-state-remove\">\n\t\t<i class=\"l-product-slide__wishlist l-product-slide__wishlist--remove\" aria-hidden=\"true\"><\/i>\n\t<\/div>\n\t<\/div><a href=\"https:\/\/ihg.bossdesign.com\/us\/projects-us\/workspace-us\/rocket-space\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <div class=\"l-product-slide__image\">\n            <img decoding=\"async\" src=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2022\/09\/17122150\/OlaTub-Boss-Design-Chair-2-.jpg\" alt=\"Ola Tub US\" \/>\n        <\/div>\n        <div class=\"l-product-slide__info js-product-slides__slide-info\">\n            <div class=\"l-product-slide__info-inner\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2022\/09\/17122150\/OlaTub-Boss-Design-Chair-2--300x225.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Ola Tub US\" srcset=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2022\/09\/17122150\/OlaTub-Boss-Design-Chair-2--300x225.jpg 300w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2022\/09\/17122150\/OlaTub-Boss-Design-Chair-2--1024x768.jpg 1024w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2022\/09\/17122150\/OlaTub-Boss-Design-Chair-2--768x576.jpg 768w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2022\/09\/17122150\/OlaTub-Boss-Design-Chair-2--600x450.jpg 600w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2022\/09\/17122150\/OlaTub-Boss-Design-Chair-2-.jpg 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>                <h5>\n                    Ola Tub US                <\/h5>\n                \n                <div\n                        hidden=\"hidden\"\n                        class=\"l-product-slide__call-to-action js-product-slides__call-to-action\">\n                    <p>\n                        <a href=\"https:\/\/ihg.bossdesign.com\/us\/product\/ola-tubconfigure\">View product<\/a>\n                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"25.052\" height=\"18.745\" viewBox=\"0 0 25.052 18.745\">\n                            <g id=\"Group_157\" data-name=\"Group 157\" transform=\"translate(0 0.354)\">\n                                <g id=\"Group_75\" data-name=\"Group 75\" transform=\"translate(0 0)\">\n                                    <g id=\"Group_74\" data-name=\"Group 74\">\n                                        <line id=\"Line_40\" data-name=\"Line 40\" x2=\"24.552\" transform=\"translate(0 9.019)\" fill=\"none\" stroke=\"#000\" stroke-linejoin=\"round\" stroke-width=\"1\"\/>\n                                        <path id=\"Path_41\" data-name=\"Path 41\" d=\"M4596.461,1377.324l9.019,9.019-9.019,9.019\" transform=\"translate(-4580.928 -1377.324)\" fill=\"none\" stroke=\"#000\" stroke-linejoin=\"round\" stroke-width=\"1\"\/>\n                                    <\/g>\n                                <\/g>\n                            <\/g>\n                        <\/svg>\n                    <\/p>\n                <\/div>\n            <\/div>\n        <\/div>\n        <div hidden=\"hidden\"\n             class=\"l-product-slide__pin js-product-slides__slide-pin\">\n            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"37.863\" height=\"37.857\" viewBox=\"0 0 37.863 37.857\">\n                <path id=\"Path_53\" data-name=\"Path 53\" d=\"M4264.124,1231.55a18.982,18.982,0,0,1,32.5-13.274,18.769,18.769,0,0,1,5.362,13.274,19.121,19.121,0,0,1-18.934,18.926,18.135,18.135,0,0,1-5.32-.814,21.083,21.083,0,0,0,1.032-1.846,31.1,31.1,0,0,0,1.478-4.733q.226-.96.671-2.591a4.786,4.786,0,0,0,1.774,1.629,7.737,7.737,0,0,0,7.022-.3,11.669,11.669,0,0,0,5.323-6.875,13.977,13.977,0,0,0-.334-9.057,10.672,10.672,0,0,0-5.951-6.027,16.44,16.44,0,0,0-10.5.333,11.8,11.8,0,0,0-7.1,6.469,15.056,15.056,0,0,0-.629,3.366,15.791,15.791,0,0,0,.11,3.253,6.4,6.4,0,0,0,1.11,2.847,5.675,5.675,0,0,0,2.363,1.922.624.624,0,0,0,.594,0c.2-.1.392-.49.587-1.181a3.6,3.6,0,0,0,.224-1.4c-.047-.1-.146-.273-.293-.519a7.205,7.205,0,0,1-1.034-5.285,9.281,9.281,0,0,1,2.292-4.693,10.273,10.273,0,0,1,6.394-2.664,8.447,8.447,0,0,1,6.246,2,7.983,7.983,0,0,1,1.81,3.918,11.963,11.963,0,0,1,0,4.4,13.258,13.258,0,0,1-1.44,3.958q-1.852,2.884-4.365,2.957a3.271,3.271,0,0,1-2.4-1.147,2.576,2.576,0,0,1-.553-2.477q.148-.812.889-3.18a16.954,16.954,0,0,0,.812-3.547q-.221-2.811-2.587-2.886a3.523,3.523,0,0,0-2.738,1.663,6.648,6.648,0,0,0-.965,3.29,8.762,8.762,0,0,0,.668,2.957q-.81,3.327-1.257,5.322c-.1.344-.37,1.406-.814,3.18a23.632,23.632,0,0,0-.739,4.067v2.072a19.491,19.491,0,0,1-8.278-7.061A18.309,18.309,0,0,1,4264.124,1231.55Z\" transform=\"translate(-4264.124 -1212.619)\"\/>\n            <\/svg>\n        <\/div>\n        <\/a><a href=\"https:\/\/ihg.bossdesign.com\/us\/product\/ola-tubconfigure\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_54009\" data-quantity=\"1\" class=\"button product_type_variable\" data-product_id=\"54009\" data-product_sku=\"\" aria-label=\"Select options for &ldquo;Ola Tub US&rdquo;\" rel=\"nofollow\">Read more<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_54009\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n        <a class=\"l-product-slide__link\" href=\"https:\/\/ihg.bossdesign.com\/us\/product\/ola-tubconfigure\"><\/a>\n    <\/div>\n<\/div><div >\n    <div\n            class=\"l-product-slide js-product-slides__slide\"\n            data-url=\"https:\/\/ihg.bossdesign.com\/us\/product\/paloma-barstool\"\n            data-media=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2023\/05\/18142023\/Paloma-Barstool-Web-Boss-Grey-.jpg\"\n            data-description=\"Paloma Barstool\"\n            aria-expanded=\"false\">\n        \n<div data-item_id=\"53699\" data-action=\"alg-wc-wl-toggle\" class=\"alg-wc-wl-btn add alg-wc-wl-thumb-btn alg-wc-wl-thumb-btn-abs alg-wc-wl-thumb-btn-loop\">\n\t<div class=\"alg-wc-wl-view-state alg-wc-wl-view-state-add\">\n\t\t<i class=\"l-product-slide__wishlist l-product-slide__wishlist--add\" aria-hidden=\"true\"><\/i>\n\t<\/div>\n\t<div class=\"alg-wc-wl-view-state alg-wc-wl-view-state-remove\">\n\t\t<i class=\"l-product-slide__wishlist l-product-slide__wishlist--remove\" aria-hidden=\"true\"><\/i>\n\t<\/div>\n\t<\/div><a href=\"https:\/\/ihg.bossdesign.com\/us\/projects-us\/workspace-us\/rocket-space\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <div class=\"l-product-slide__image\">\n            <img decoding=\"async\" src=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2023\/05\/18142023\/Paloma-Barstool-Web-Boss-Grey-.jpg\" alt=\"Paloma Barstool\" \/>\n        <\/div>\n        <div class=\"l-product-slide__info js-product-slides__slide-info\">\n            <div class=\"l-product-slide__info-inner\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2023\/05\/18142023\/Paloma-Barstool-Web-Boss-Grey--300x225.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Paloma Barstool\" srcset=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2023\/05\/18142023\/Paloma-Barstool-Web-Boss-Grey--300x225.jpg 300w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2023\/05\/18142023\/Paloma-Barstool-Web-Boss-Grey--1024x768.jpg 1024w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2023\/05\/18142023\/Paloma-Barstool-Web-Boss-Grey--768x576.jpg 768w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2023\/05\/18142023\/Paloma-Barstool-Web-Boss-Grey--1536x1152.jpg 1536w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2023\/05\/18142023\/Paloma-Barstool-Web-Boss-Grey--600x450.jpg 600w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2023\/05\/18142023\/Paloma-Barstool-Web-Boss-Grey-.jpg 1707w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>                <h5>\n                    Paloma Barstool                <\/h5>\n                \n                <div\n                        hidden=\"hidden\"\n                        class=\"l-product-slide__call-to-action js-product-slides__call-to-action\">\n                    <p>\n                        <a href=\"https:\/\/ihg.bossdesign.com\/us\/product\/paloma-barstool\">View product<\/a>\n                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"25.052\" height=\"18.745\" viewBox=\"0 0 25.052 18.745\">\n                            <g id=\"Group_157\" data-name=\"Group 157\" transform=\"translate(0 0.354)\">\n                                <g id=\"Group_75\" data-name=\"Group 75\" transform=\"translate(0 0)\">\n                                    <g id=\"Group_74\" data-name=\"Group 74\">\n                                        <line id=\"Line_40\" data-name=\"Line 40\" x2=\"24.552\" transform=\"translate(0 9.019)\" fill=\"none\" stroke=\"#000\" stroke-linejoin=\"round\" stroke-width=\"1\"\/>\n                                        <path id=\"Path_41\" data-name=\"Path 41\" d=\"M4596.461,1377.324l9.019,9.019-9.019,9.019\" transform=\"translate(-4580.928 -1377.324)\" fill=\"none\" stroke=\"#000\" stroke-linejoin=\"round\" stroke-width=\"1\"\/>\n                                    <\/g>\n                                <\/g>\n                            <\/g>\n                        <\/svg>\n                    <\/p>\n                <\/div>\n            <\/div>\n        <\/div>\n        <div hidden=\"hidden\"\n             class=\"l-product-slide__pin js-product-slides__slide-pin\">\n            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"37.863\" height=\"37.857\" viewBox=\"0 0 37.863 37.857\">\n                <path id=\"Path_53\" data-name=\"Path 53\" d=\"M4264.124,1231.55a18.982,18.982,0,0,1,32.5-13.274,18.769,18.769,0,0,1,5.362,13.274,19.121,19.121,0,0,1-18.934,18.926,18.135,18.135,0,0,1-5.32-.814,21.083,21.083,0,0,0,1.032-1.846,31.1,31.1,0,0,0,1.478-4.733q.226-.96.671-2.591a4.786,4.786,0,0,0,1.774,1.629,7.737,7.737,0,0,0,7.022-.3,11.669,11.669,0,0,0,5.323-6.875,13.977,13.977,0,0,0-.334-9.057,10.672,10.672,0,0,0-5.951-6.027,16.44,16.44,0,0,0-10.5.333,11.8,11.8,0,0,0-7.1,6.469,15.056,15.056,0,0,0-.629,3.366,15.791,15.791,0,0,0,.11,3.253,6.4,6.4,0,0,0,1.11,2.847,5.675,5.675,0,0,0,2.363,1.922.624.624,0,0,0,.594,0c.2-.1.392-.49.587-1.181a3.6,3.6,0,0,0,.224-1.4c-.047-.1-.146-.273-.293-.519a7.205,7.205,0,0,1-1.034-5.285,9.281,9.281,0,0,1,2.292-4.693,10.273,10.273,0,0,1,6.394-2.664,8.447,8.447,0,0,1,6.246,2,7.983,7.983,0,0,1,1.81,3.918,11.963,11.963,0,0,1,0,4.4,13.258,13.258,0,0,1-1.44,3.958q-1.852,2.884-4.365,2.957a3.271,3.271,0,0,1-2.4-1.147,2.576,2.576,0,0,1-.553-2.477q.148-.812.889-3.18a16.954,16.954,0,0,0,.812-3.547q-.221-2.811-2.587-2.886a3.523,3.523,0,0,0-2.738,1.663,6.648,6.648,0,0,0-.965,3.29,8.762,8.762,0,0,0,.668,2.957q-.81,3.327-1.257,5.322c-.1.344-.37,1.406-.814,3.18a23.632,23.632,0,0,0-.739,4.067v2.072a19.491,19.491,0,0,1-8.278-7.061A18.309,18.309,0,0,1,4264.124,1231.55Z\" transform=\"translate(-4264.124 -1212.619)\"\/>\n            <\/svg>\n        <\/div>\n        <\/a><a href=\"https:\/\/ihg.bossdesign.com\/us\/product\/paloma-barstool\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_53699\" data-quantity=\"1\" class=\"button product_type_variable\" data-product_id=\"53699\" data-product_sku=\"\" aria-label=\"Select options for &ldquo;Paloma Barstool&rdquo;\" rel=\"nofollow\">Read more<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_53699\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n        <a class=\"l-product-slide__link\" href=\"https:\/\/ihg.bossdesign.com\/us\/product\/paloma-barstool\"><\/a>\n    <\/div>\n<\/div><div >\n    <div\n            class=\"l-product-slide js-product-slides__slide\"\n            data-url=\"https:\/\/ihg.bossdesign.com\/us\/product\/kato\"\n            data-media=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2023\/01\/25082623\/KATO-WEB-FINAL-GREY.jpg\"\n            data-description=\"Kato\"\n            aria-expanded=\"false\">\n        \n<div data-item_id=\"53695\" data-action=\"alg-wc-wl-toggle\" class=\"alg-wc-wl-btn add alg-wc-wl-thumb-btn alg-wc-wl-thumb-btn-abs alg-wc-wl-thumb-btn-loop\">\n\t<div class=\"alg-wc-wl-view-state alg-wc-wl-view-state-add\">\n\t\t<i class=\"l-product-slide__wishlist l-product-slide__wishlist--add\" aria-hidden=\"true\"><\/i>\n\t<\/div>\n\t<div class=\"alg-wc-wl-view-state alg-wc-wl-view-state-remove\">\n\t\t<i class=\"l-product-slide__wishlist l-product-slide__wishlist--remove\" aria-hidden=\"true\"><\/i>\n\t<\/div>\n\t<\/div><a href=\"https:\/\/ihg.bossdesign.com\/us\/projects-us\/workspace-us\/rocket-space\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <div class=\"l-product-slide__image\">\n            <img decoding=\"async\" src=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2023\/01\/25082623\/KATO-WEB-FINAL-GREY.jpg\" alt=\"Kato\" \/>\n        <\/div>\n        <div class=\"l-product-slide__info js-product-slides__slide-info\">\n            <div class=\"l-product-slide__info-inner\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2023\/01\/25082623\/KATO-WEB-FINAL-GREY-300x225.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Kato\" srcset=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2023\/01\/25082623\/KATO-WEB-FINAL-GREY-300x225.jpg 300w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2023\/01\/25082623\/KATO-WEB-FINAL-GREY-1024x768.jpg 1024w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2023\/01\/25082623\/KATO-WEB-FINAL-GREY-768x576.jpg 768w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2023\/01\/25082623\/KATO-WEB-FINAL-GREY-1536x1152.jpg 1536w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2023\/01\/25082623\/KATO-WEB-FINAL-GREY-600x450.jpg 600w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2023\/01\/25082623\/KATO-WEB-FINAL-GREY.jpg 1707w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>                <h5>\n                    Kato                <\/h5>\n                \n                <div\n                        hidden=\"hidden\"\n                        class=\"l-product-slide__call-to-action js-product-slides__call-to-action\">\n                    <p>\n                        <a href=\"https:\/\/ihg.bossdesign.com\/us\/product\/kato\">View product<\/a>\n                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"25.052\" height=\"18.745\" viewBox=\"0 0 25.052 18.745\">\n                            <g id=\"Group_157\" data-name=\"Group 157\" transform=\"translate(0 0.354)\">\n                                <g id=\"Group_75\" data-name=\"Group 75\" transform=\"translate(0 0)\">\n                                    <g id=\"Group_74\" data-name=\"Group 74\">\n                                        <line id=\"Line_40\" data-name=\"Line 40\" x2=\"24.552\" transform=\"translate(0 9.019)\" fill=\"none\" stroke=\"#000\" stroke-linejoin=\"round\" stroke-width=\"1\"\/>\n                                        <path id=\"Path_41\" data-name=\"Path 41\" d=\"M4596.461,1377.324l9.019,9.019-9.019,9.019\" transform=\"translate(-4580.928 -1377.324)\" fill=\"none\" stroke=\"#000\" stroke-linejoin=\"round\" stroke-width=\"1\"\/>\n                                    <\/g>\n                                <\/g>\n                            <\/g>\n                        <\/svg>\n                    <\/p>\n                <\/div>\n            <\/div>\n        <\/div>\n        <div hidden=\"hidden\"\n             class=\"l-product-slide__pin js-product-slides__slide-pin\">\n            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"37.863\" height=\"37.857\" viewBox=\"0 0 37.863 37.857\">\n                <path id=\"Path_53\" data-name=\"Path 53\" d=\"M4264.124,1231.55a18.982,18.982,0,0,1,32.5-13.274,18.769,18.769,0,0,1,5.362,13.274,19.121,19.121,0,0,1-18.934,18.926,18.135,18.135,0,0,1-5.32-.814,21.083,21.083,0,0,0,1.032-1.846,31.1,31.1,0,0,0,1.478-4.733q.226-.96.671-2.591a4.786,4.786,0,0,0,1.774,1.629,7.737,7.737,0,0,0,7.022-.3,11.669,11.669,0,0,0,5.323-6.875,13.977,13.977,0,0,0-.334-9.057,10.672,10.672,0,0,0-5.951-6.027,16.44,16.44,0,0,0-10.5.333,11.8,11.8,0,0,0-7.1,6.469,15.056,15.056,0,0,0-.629,3.366,15.791,15.791,0,0,0,.11,3.253,6.4,6.4,0,0,0,1.11,2.847,5.675,5.675,0,0,0,2.363,1.922.624.624,0,0,0,.594,0c.2-.1.392-.49.587-1.181a3.6,3.6,0,0,0,.224-1.4c-.047-.1-.146-.273-.293-.519a7.205,7.205,0,0,1-1.034-5.285,9.281,9.281,0,0,1,2.292-4.693,10.273,10.273,0,0,1,6.394-2.664,8.447,8.447,0,0,1,6.246,2,7.983,7.983,0,0,1,1.81,3.918,11.963,11.963,0,0,1,0,4.4,13.258,13.258,0,0,1-1.44,3.958q-1.852,2.884-4.365,2.957a3.271,3.271,0,0,1-2.4-1.147,2.576,2.576,0,0,1-.553-2.477q.148-.812.889-3.18a16.954,16.954,0,0,0,.812-3.547q-.221-2.811-2.587-2.886a3.523,3.523,0,0,0-2.738,1.663,6.648,6.648,0,0,0-.965,3.29,8.762,8.762,0,0,0,.668,2.957q-.81,3.327-1.257,5.322c-.1.344-.37,1.406-.814,3.18a23.632,23.632,0,0,0-.739,4.067v2.072a19.491,19.491,0,0,1-8.278-7.061A18.309,18.309,0,0,1,4264.124,1231.55Z\" transform=\"translate(-4264.124 -1212.619)\"\/>\n            <\/svg>\n        <\/div>\n        <\/a><a href=\"https:\/\/ihg.bossdesign.com\/us\/product\/kato\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_53695\" data-quantity=\"1\" class=\"button product_type_variable\" data-product_id=\"53695\" data-product_sku=\"\" aria-label=\"Select options for &ldquo;Kato&rdquo;\" rel=\"nofollow\">Read more<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_53695\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n        <a class=\"l-product-slide__link\" href=\"https:\/\/ihg.bossdesign.com\/us\/product\/kato\"><\/a>\n    <\/div>\n<\/div><div >\n    <div\n            class=\"l-product-slide js-product-slides__slide\"\n            data-url=\"https:\/\/ihg.bossdesign.com\/us\/product\/hart\"\n            data-media=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2023\/01\/19104620\/Hart-Boss-Design-Stool-0.jpg\"\n            data-description=\"Hart\"\n            aria-expanded=\"false\">\n        \n<div data-item_id=\"53702\" data-action=\"alg-wc-wl-toggle\" class=\"alg-wc-wl-btn add alg-wc-wl-thumb-btn alg-wc-wl-thumb-btn-abs alg-wc-wl-thumb-btn-loop\">\n\t<div class=\"alg-wc-wl-view-state alg-wc-wl-view-state-add\">\n\t\t<i class=\"l-product-slide__wishlist l-product-slide__wishlist--add\" aria-hidden=\"true\"><\/i>\n\t<\/div>\n\t<div class=\"alg-wc-wl-view-state alg-wc-wl-view-state-remove\">\n\t\t<i class=\"l-product-slide__wishlist l-product-slide__wishlist--remove\" aria-hidden=\"true\"><\/i>\n\t<\/div>\n\t<\/div><a href=\"https:\/\/ihg.bossdesign.com\/us\/projects-us\/workspace-us\/rocket-space\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <div class=\"l-product-slide__image\">\n            <img decoding=\"async\" src=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2023\/01\/19104620\/Hart-Boss-Design-Stool-0.jpg\" alt=\"Hart\" \/>\n        <\/div>\n        <div class=\"l-product-slide__info js-product-slides__slide-info\">\n            <div class=\"l-product-slide__info-inner\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2023\/01\/19104620\/Hart-Boss-Design-Stool-0-300x225.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Hart\" srcset=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2023\/01\/19104620\/Hart-Boss-Design-Stool-0-300x225.jpg 300w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2023\/01\/19104620\/Hart-Boss-Design-Stool-0-1024x768.jpg 1024w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2023\/01\/19104620\/Hart-Boss-Design-Stool-0-768x576.jpg 768w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2023\/01\/19104620\/Hart-Boss-Design-Stool-0-600x450.jpg 600w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2023\/01\/19104620\/Hart-Boss-Design-Stool-0.jpg 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>                <h5>\n                    Hart                <\/h5>\n                \n                <div\n                        hidden=\"hidden\"\n                        class=\"l-product-slide__call-to-action js-product-slides__call-to-action\">\n                    <p>\n                        <a href=\"https:\/\/ihg.bossdesign.com\/us\/product\/hart\">View product<\/a>\n                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"25.052\" height=\"18.745\" viewBox=\"0 0 25.052 18.745\">\n                            <g id=\"Group_157\" data-name=\"Group 157\" transform=\"translate(0 0.354)\">\n                                <g id=\"Group_75\" data-name=\"Group 75\" transform=\"translate(0 0)\">\n                                    <g id=\"Group_74\" data-name=\"Group 74\">\n                                        <line id=\"Line_40\" data-name=\"Line 40\" x2=\"24.552\" transform=\"translate(0 9.019)\" fill=\"none\" stroke=\"#000\" stroke-linejoin=\"round\" stroke-width=\"1\"\/>\n                                        <path id=\"Path_41\" data-name=\"Path 41\" d=\"M4596.461,1377.324l9.019,9.019-9.019,9.019\" transform=\"translate(-4580.928 -1377.324)\" fill=\"none\" stroke=\"#000\" stroke-linejoin=\"round\" stroke-width=\"1\"\/>\n                                    <\/g>\n                                <\/g>\n                            <\/g>\n                        <\/svg>\n                    <\/p>\n                <\/div>\n            <\/div>\n        <\/div>\n        <div hidden=\"hidden\"\n             class=\"l-product-slide__pin js-product-slides__slide-pin\">\n            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"37.863\" height=\"37.857\" viewBox=\"0 0 37.863 37.857\">\n                <path id=\"Path_53\" data-name=\"Path 53\" d=\"M4264.124,1231.55a18.982,18.982,0,0,1,32.5-13.274,18.769,18.769,0,0,1,5.362,13.274,19.121,19.121,0,0,1-18.934,18.926,18.135,18.135,0,0,1-5.32-.814,21.083,21.083,0,0,0,1.032-1.846,31.1,31.1,0,0,0,1.478-4.733q.226-.96.671-2.591a4.786,4.786,0,0,0,1.774,1.629,7.737,7.737,0,0,0,7.022-.3,11.669,11.669,0,0,0,5.323-6.875,13.977,13.977,0,0,0-.334-9.057,10.672,10.672,0,0,0-5.951-6.027,16.44,16.44,0,0,0-10.5.333,11.8,11.8,0,0,0-7.1,6.469,15.056,15.056,0,0,0-.629,3.366,15.791,15.791,0,0,0,.11,3.253,6.4,6.4,0,0,0,1.11,2.847,5.675,5.675,0,0,0,2.363,1.922.624.624,0,0,0,.594,0c.2-.1.392-.49.587-1.181a3.6,3.6,0,0,0,.224-1.4c-.047-.1-.146-.273-.293-.519a7.205,7.205,0,0,1-1.034-5.285,9.281,9.281,0,0,1,2.292-4.693,10.273,10.273,0,0,1,6.394-2.664,8.447,8.447,0,0,1,6.246,2,7.983,7.983,0,0,1,1.81,3.918,11.963,11.963,0,0,1,0,4.4,13.258,13.258,0,0,1-1.44,3.958q-1.852,2.884-4.365,2.957a3.271,3.271,0,0,1-2.4-1.147,2.576,2.576,0,0,1-.553-2.477q.148-.812.889-3.18a16.954,16.954,0,0,0,.812-3.547q-.221-2.811-2.587-2.886a3.523,3.523,0,0,0-2.738,1.663,6.648,6.648,0,0,0-.965,3.29,8.762,8.762,0,0,0,.668,2.957q-.81,3.327-1.257,5.322c-.1.344-.37,1.406-.814,3.18a23.632,23.632,0,0,0-.739,4.067v2.072a19.491,19.491,0,0,1-8.278-7.061A18.309,18.309,0,0,1,4264.124,1231.55Z\" transform=\"translate(-4264.124 -1212.619)\"\/>\n            <\/svg>\n        <\/div>\n        <\/a><a href=\"https:\/\/ihg.bossdesign.com\/us\/product\/hart\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_53702\" data-quantity=\"1\" class=\"button product_type_variable\" data-product_id=\"53702\" data-product_sku=\"\" aria-label=\"Select options for &ldquo;Hart&rdquo;\" rel=\"nofollow\">Read more<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_53702\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n        <a class=\"l-product-slide__link\" href=\"https:\/\/ihg.bossdesign.com\/us\/product\/hart\"><\/a>\n    <\/div>\n<\/div><div >\n    <div\n            class=\"l-product-slide js-product-slides__slide\"\n            data-url=\"https:\/\/ihg.bossdesign.com\/us\/product\/ola-tub\"\n            data-media=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2022\/09\/17122150\/OlaTub-Boss-Design-Chair-2-.jpg\"\n            data-description=\"Ola Tub\"\n            aria-expanded=\"false\">\n        \n<div data-item_id=\"52387\" data-action=\"alg-wc-wl-toggle\" class=\"alg-wc-wl-btn add alg-wc-wl-thumb-btn alg-wc-wl-thumb-btn-abs alg-wc-wl-thumb-btn-loop\">\n\t<div class=\"alg-wc-wl-view-state alg-wc-wl-view-state-add\">\n\t\t<i class=\"l-product-slide__wishlist l-product-slide__wishlist--add\" aria-hidden=\"true\"><\/i>\n\t<\/div>\n\t<div class=\"alg-wc-wl-view-state alg-wc-wl-view-state-remove\">\n\t\t<i class=\"l-product-slide__wishlist l-product-slide__wishlist--remove\" aria-hidden=\"true\"><\/i>\n\t<\/div>\n\t<\/div><a href=\"https:\/\/ihg.bossdesign.com\/us\/projects-us\/workspace-us\/rocket-space\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <div class=\"l-product-slide__image\">\n            <img decoding=\"async\" src=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2022\/09\/17122150\/OlaTub-Boss-Design-Chair-2-.jpg\" alt=\"Ola Tub\" \/>\n        <\/div>\n        <div class=\"l-product-slide__info js-product-slides__slide-info\">\n            <div class=\"l-product-slide__info-inner\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2022\/09\/17122150\/OlaTub-Boss-Design-Chair-2--300x225.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Ola Tub\" srcset=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2022\/09\/17122150\/OlaTub-Boss-Design-Chair-2--300x225.jpg 300w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2022\/09\/17122150\/OlaTub-Boss-Design-Chair-2--1024x768.jpg 1024w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2022\/09\/17122150\/OlaTub-Boss-Design-Chair-2--768x576.jpg 768w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2022\/09\/17122150\/OlaTub-Boss-Design-Chair-2--600x450.jpg 600w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2022\/09\/17122150\/OlaTub-Boss-Design-Chair-2-.jpg 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>                <h5>\n                    Ola Tub                <\/h5>\n                \n                <div\n                        hidden=\"hidden\"\n                        class=\"l-product-slide__call-to-action js-product-slides__call-to-action\">\n                    <p>\n                        <a href=\"https:\/\/ihg.bossdesign.com\/us\/product\/ola-tub\">View product<\/a>\n                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"25.052\" height=\"18.745\" viewBox=\"0 0 25.052 18.745\">\n                            <g id=\"Group_157\" data-name=\"Group 157\" transform=\"translate(0 0.354)\">\n                                <g id=\"Group_75\" data-name=\"Group 75\" transform=\"translate(0 0)\">\n                                    <g id=\"Group_74\" data-name=\"Group 74\">\n                                        <line id=\"Line_40\" data-name=\"Line 40\" x2=\"24.552\" transform=\"translate(0 9.019)\" fill=\"none\" stroke=\"#000\" stroke-linejoin=\"round\" stroke-width=\"1\"\/>\n                                        <path id=\"Path_41\" data-name=\"Path 41\" d=\"M4596.461,1377.324l9.019,9.019-9.019,9.019\" transform=\"translate(-4580.928 -1377.324)\" fill=\"none\" stroke=\"#000\" stroke-linejoin=\"round\" stroke-width=\"1\"\/>\n                                    <\/g>\n                                <\/g>\n                            <\/g>\n                        <\/svg>\n                    <\/p>\n                <\/div>\n            <\/div>\n        <\/div>\n        <div hidden=\"hidden\"\n             class=\"l-product-slide__pin js-product-slides__slide-pin\">\n            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"37.863\" height=\"37.857\" viewBox=\"0 0 37.863 37.857\">\n                <path id=\"Path_53\" data-name=\"Path 53\" d=\"M4264.124,1231.55a18.982,18.982,0,0,1,32.5-13.274,18.769,18.769,0,0,1,5.362,13.274,19.121,19.121,0,0,1-18.934,18.926,18.135,18.135,0,0,1-5.32-.814,21.083,21.083,0,0,0,1.032-1.846,31.1,31.1,0,0,0,1.478-4.733q.226-.96.671-2.591a4.786,4.786,0,0,0,1.774,1.629,7.737,7.737,0,0,0,7.022-.3,11.669,11.669,0,0,0,5.323-6.875,13.977,13.977,0,0,0-.334-9.057,10.672,10.672,0,0,0-5.951-6.027,16.44,16.44,0,0,0-10.5.333,11.8,11.8,0,0,0-7.1,6.469,15.056,15.056,0,0,0-.629,3.366,15.791,15.791,0,0,0,.11,3.253,6.4,6.4,0,0,0,1.11,2.847,5.675,5.675,0,0,0,2.363,1.922.624.624,0,0,0,.594,0c.2-.1.392-.49.587-1.181a3.6,3.6,0,0,0,.224-1.4c-.047-.1-.146-.273-.293-.519a7.205,7.205,0,0,1-1.034-5.285,9.281,9.281,0,0,1,2.292-4.693,10.273,10.273,0,0,1,6.394-2.664,8.447,8.447,0,0,1,6.246,2,7.983,7.983,0,0,1,1.81,3.918,11.963,11.963,0,0,1,0,4.4,13.258,13.258,0,0,1-1.44,3.958q-1.852,2.884-4.365,2.957a3.271,3.271,0,0,1-2.4-1.147,2.576,2.576,0,0,1-.553-2.477q.148-.812.889-3.18a16.954,16.954,0,0,0,.812-3.547q-.221-2.811-2.587-2.886a3.523,3.523,0,0,0-2.738,1.663,6.648,6.648,0,0,0-.965,3.29,8.762,8.762,0,0,0,.668,2.957q-.81,3.327-1.257,5.322c-.1.344-.37,1.406-.814,3.18a23.632,23.632,0,0,0-.739,4.067v2.072a19.491,19.491,0,0,1-8.278-7.061A18.309,18.309,0,0,1,4264.124,1231.55Z\" transform=\"translate(-4264.124 -1212.619)\"\/>\n            <\/svg>\n        <\/div>\n        <\/a><a href=\"https:\/\/ihg.bossdesign.com\/us\/product\/ola-tub\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_52387\" data-quantity=\"1\" class=\"button product_type_variable\" data-product_id=\"52387\" data-product_sku=\"\" aria-label=\"Select options for &ldquo;Ola Tub&rdquo;\" rel=\"nofollow\">Read more<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_52387\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n        <a class=\"l-product-slide__link\" href=\"https:\/\/ihg.bossdesign.com\/us\/product\/ola-tub\"><\/a>\n    <\/div>\n<\/div><div >\n    <div\n            class=\"l-product-slide js-product-slides__slide\"\n            data-url=\"https:\/\/ihg.bossdesign.com\/us\/product\/ola-plush\"\n            data-media=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2022\/08\/30085208\/OLA-Plush-Grey.jpg\"\n            data-description=\"Ola Plush\"\n            aria-expanded=\"false\">\n        \n<div data-item_id=\"52397\" data-action=\"alg-wc-wl-toggle\" class=\"alg-wc-wl-btn add alg-wc-wl-thumb-btn alg-wc-wl-thumb-btn-abs alg-wc-wl-thumb-btn-loop\">\n\t<div class=\"alg-wc-wl-view-state alg-wc-wl-view-state-add\">\n\t\t<i class=\"l-product-slide__wishlist l-product-slide__wishlist--add\" aria-hidden=\"true\"><\/i>\n\t<\/div>\n\t<div class=\"alg-wc-wl-view-state alg-wc-wl-view-state-remove\">\n\t\t<i class=\"l-product-slide__wishlist l-product-slide__wishlist--remove\" aria-hidden=\"true\"><\/i>\n\t<\/div>\n\t<\/div><a href=\"https:\/\/ihg.bossdesign.com\/us\/projects-us\/workspace-us\/rocket-space\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <div class=\"l-product-slide__image\">\n            <img decoding=\"async\" src=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2022\/08\/30085208\/OLA-Plush-Grey.jpg\" alt=\"Ola Plush\" \/>\n        <\/div>\n        <div class=\"l-product-slide__info js-product-slides__slide-info\">\n            <div class=\"l-product-slide__info-inner\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2022\/08\/30085208\/OLA-Plush-Grey-300x225.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Ola Plush\" srcset=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2022\/08\/30085208\/OLA-Plush-Grey-300x225.jpg 300w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2022\/08\/30085208\/OLA-Plush-Grey-1024x768.jpg 1024w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2022\/08\/30085208\/OLA-Plush-Grey-768x576.jpg 768w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2022\/08\/30085208\/OLA-Plush-Grey-1536x1152.jpg 1536w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2022\/08\/30085208\/OLA-Plush-Grey-600x450.jpg 600w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2022\/08\/30085208\/OLA-Plush-Grey.jpg 1707w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>                <h5>\n                    Ola Plush                <\/h5>\n                \n                <div\n                        hidden=\"hidden\"\n                        class=\"l-product-slide__call-to-action js-product-slides__call-to-action\">\n                    <p>\n                        <a href=\"https:\/\/ihg.bossdesign.com\/us\/product\/ola-plush\">View product<\/a>\n                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"25.052\" height=\"18.745\" viewBox=\"0 0 25.052 18.745\">\n                            <g id=\"Group_157\" data-name=\"Group 157\" transform=\"translate(0 0.354)\">\n                                <g id=\"Group_75\" data-name=\"Group 75\" transform=\"translate(0 0)\">\n                                    <g id=\"Group_74\" data-name=\"Group 74\">\n                                        <line id=\"Line_40\" data-name=\"Line 40\" x2=\"24.552\" transform=\"translate(0 9.019)\" fill=\"none\" stroke=\"#000\" stroke-linejoin=\"round\" stroke-width=\"1\"\/>\n                                        <path id=\"Path_41\" data-name=\"Path 41\" d=\"M4596.461,1377.324l9.019,9.019-9.019,9.019\" transform=\"translate(-4580.928 -1377.324)\" fill=\"none\" stroke=\"#000\" stroke-linejoin=\"round\" stroke-width=\"1\"\/>\n                                    <\/g>\n                                <\/g>\n                            <\/g>\n                        <\/svg>\n                    <\/p>\n                <\/div>\n            <\/div>\n        <\/div>\n        <div hidden=\"hidden\"\n             class=\"l-product-slide__pin js-product-slides__slide-pin\">\n            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"37.863\" height=\"37.857\" viewBox=\"0 0 37.863 37.857\">\n                <path id=\"Path_53\" data-name=\"Path 53\" d=\"M4264.124,1231.55a18.982,18.982,0,0,1,32.5-13.274,18.769,18.769,0,0,1,5.362,13.274,19.121,19.121,0,0,1-18.934,18.926,18.135,18.135,0,0,1-5.32-.814,21.083,21.083,0,0,0,1.032-1.846,31.1,31.1,0,0,0,1.478-4.733q.226-.96.671-2.591a4.786,4.786,0,0,0,1.774,1.629,7.737,7.737,0,0,0,7.022-.3,11.669,11.669,0,0,0,5.323-6.875,13.977,13.977,0,0,0-.334-9.057,10.672,10.672,0,0,0-5.951-6.027,16.44,16.44,0,0,0-10.5.333,11.8,11.8,0,0,0-7.1,6.469,15.056,15.056,0,0,0-.629,3.366,15.791,15.791,0,0,0,.11,3.253,6.4,6.4,0,0,0,1.11,2.847,5.675,5.675,0,0,0,2.363,1.922.624.624,0,0,0,.594,0c.2-.1.392-.49.587-1.181a3.6,3.6,0,0,0,.224-1.4c-.047-.1-.146-.273-.293-.519a7.205,7.205,0,0,1-1.034-5.285,9.281,9.281,0,0,1,2.292-4.693,10.273,10.273,0,0,1,6.394-2.664,8.447,8.447,0,0,1,6.246,2,7.983,7.983,0,0,1,1.81,3.918,11.963,11.963,0,0,1,0,4.4,13.258,13.258,0,0,1-1.44,3.958q-1.852,2.884-4.365,2.957a3.271,3.271,0,0,1-2.4-1.147,2.576,2.576,0,0,1-.553-2.477q.148-.812.889-3.18a16.954,16.954,0,0,0,.812-3.547q-.221-2.811-2.587-2.886a3.523,3.523,0,0,0-2.738,1.663,6.648,6.648,0,0,0-.965,3.29,8.762,8.762,0,0,0,.668,2.957q-.81,3.327-1.257,5.322c-.1.344-.37,1.406-.814,3.18a23.632,23.632,0,0,0-.739,4.067v2.072a19.491,19.491,0,0,1-8.278-7.061A18.309,18.309,0,0,1,4264.124,1231.55Z\" transform=\"translate(-4264.124 -1212.619)\"\/>\n            <\/svg>\n        <\/div>\n        <\/a><a href=\"https:\/\/ihg.bossdesign.com\/us\/product\/ola-plush\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_52397\" data-quantity=\"1\" class=\"button product_type_variable\" data-product_id=\"52397\" data-product_sku=\"\" aria-label=\"Select options for &ldquo;Ola Plush&rdquo;\" rel=\"nofollow\">Read more<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_52397\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n        <a class=\"l-product-slide__link\" href=\"https:\/\/ihg.bossdesign.com\/us\/product\/ola-plush\"><\/a>\n    <\/div>\n<\/div><div >\n    <div\n            class=\"l-product-slide js-product-slides__slide\"\n            data-url=\"https:\/\/ihg.bossdesign.com\/us\/product\/sia\"\n            data-media=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2022\/08\/16144958\/Sia-Boss-Design-Task-Chair-02.jpg\"\n            data-description=\"Sia\"\n            aria-expanded=\"false\">\n        \n<div data-item_id=\"52398\" data-action=\"alg-wc-wl-toggle\" class=\"alg-wc-wl-btn add alg-wc-wl-thumb-btn alg-wc-wl-thumb-btn-abs alg-wc-wl-thumb-btn-loop\">\n\t<div class=\"alg-wc-wl-view-state alg-wc-wl-view-state-add\">\n\t\t<i class=\"l-product-slide__wishlist l-product-slide__wishlist--add\" aria-hidden=\"true\"><\/i>\n\t<\/div>\n\t<div class=\"alg-wc-wl-view-state alg-wc-wl-view-state-remove\">\n\t\t<i class=\"l-product-slide__wishlist l-product-slide__wishlist--remove\" aria-hidden=\"true\"><\/i>\n\t<\/div>\n\t<\/div><a href=\"https:\/\/ihg.bossdesign.com\/us\/projects-us\/workspace-us\/rocket-space\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <div class=\"l-product-slide__image\">\n            <img decoding=\"async\" src=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2022\/08\/16144958\/Sia-Boss-Design-Task-Chair-02.jpg\" alt=\"Sia\" \/>\n        <\/div>\n        <div class=\"l-product-slide__info js-product-slides__slide-info\">\n            <div class=\"l-product-slide__info-inner\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2022\/08\/16144958\/Sia-Boss-Design-Task-Chair-02-300x225.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Sia\" srcset=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2022\/08\/16144958\/Sia-Boss-Design-Task-Chair-02-300x225.jpg 300w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2022\/08\/16144958\/Sia-Boss-Design-Task-Chair-02-1024x768.jpg 1024w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2022\/08\/16144958\/Sia-Boss-Design-Task-Chair-02-768x576.jpg 768w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2022\/08\/16144958\/Sia-Boss-Design-Task-Chair-02-600x450.jpg 600w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2022\/08\/16144958\/Sia-Boss-Design-Task-Chair-02.jpg 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>                <h5>\n                    Sia                <\/h5>\n                \n                <div\n                        hidden=\"hidden\"\n                        class=\"l-product-slide__call-to-action js-product-slides__call-to-action\">\n                    <p>\n                        <a href=\"https:\/\/ihg.bossdesign.com\/us\/product\/sia\">View product<\/a>\n                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"25.052\" height=\"18.745\" viewBox=\"0 0 25.052 18.745\">\n                            <g id=\"Group_157\" data-name=\"Group 157\" transform=\"translate(0 0.354)\">\n                                <g id=\"Group_75\" data-name=\"Group 75\" transform=\"translate(0 0)\">\n                                    <g id=\"Group_74\" data-name=\"Group 74\">\n                                        <line id=\"Line_40\" data-name=\"Line 40\" x2=\"24.552\" transform=\"translate(0 9.019)\" fill=\"none\" stroke=\"#000\" stroke-linejoin=\"round\" stroke-width=\"1\"\/>\n                                        <path id=\"Path_41\" data-name=\"Path 41\" d=\"M4596.461,1377.324l9.019,9.019-9.019,9.019\" transform=\"translate(-4580.928 -1377.324)\" fill=\"none\" stroke=\"#000\" stroke-linejoin=\"round\" stroke-width=\"1\"\/>\n                                    <\/g>\n                                <\/g>\n                            <\/g>\n                        <\/svg>\n                    <\/p>\n                <\/div>\n            <\/div>\n        <\/div>\n        <div hidden=\"hidden\"\n             class=\"l-product-slide__pin js-product-slides__slide-pin\">\n            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"37.863\" height=\"37.857\" viewBox=\"0 0 37.863 37.857\">\n                <path id=\"Path_53\" data-name=\"Path 53\" d=\"M4264.124,1231.55a18.982,18.982,0,0,1,32.5-13.274,18.769,18.769,0,0,1,5.362,13.274,19.121,19.121,0,0,1-18.934,18.926,18.135,18.135,0,0,1-5.32-.814,21.083,21.083,0,0,0,1.032-1.846,31.1,31.1,0,0,0,1.478-4.733q.226-.96.671-2.591a4.786,4.786,0,0,0,1.774,1.629,7.737,7.737,0,0,0,7.022-.3,11.669,11.669,0,0,0,5.323-6.875,13.977,13.977,0,0,0-.334-9.057,10.672,10.672,0,0,0-5.951-6.027,16.44,16.44,0,0,0-10.5.333,11.8,11.8,0,0,0-7.1,6.469,15.056,15.056,0,0,0-.629,3.366,15.791,15.791,0,0,0,.11,3.253,6.4,6.4,0,0,0,1.11,2.847,5.675,5.675,0,0,0,2.363,1.922.624.624,0,0,0,.594,0c.2-.1.392-.49.587-1.181a3.6,3.6,0,0,0,.224-1.4c-.047-.1-.146-.273-.293-.519a7.205,7.205,0,0,1-1.034-5.285,9.281,9.281,0,0,1,2.292-4.693,10.273,10.273,0,0,1,6.394-2.664,8.447,8.447,0,0,1,6.246,2,7.983,7.983,0,0,1,1.81,3.918,11.963,11.963,0,0,1,0,4.4,13.258,13.258,0,0,1-1.44,3.958q-1.852,2.884-4.365,2.957a3.271,3.271,0,0,1-2.4-1.147,2.576,2.576,0,0,1-.553-2.477q.148-.812.889-3.18a16.954,16.954,0,0,0,.812-3.547q-.221-2.811-2.587-2.886a3.523,3.523,0,0,0-2.738,1.663,6.648,6.648,0,0,0-.965,3.29,8.762,8.762,0,0,0,.668,2.957q-.81,3.327-1.257,5.322c-.1.344-.37,1.406-.814,3.18a23.632,23.632,0,0,0-.739,4.067v2.072a19.491,19.491,0,0,1-8.278-7.061A18.309,18.309,0,0,1,4264.124,1231.55Z\" transform=\"translate(-4264.124 -1212.619)\"\/>\n            <\/svg>\n        <\/div>\n        <\/a><a href=\"https:\/\/ihg.bossdesign.com\/us\/product\/sia\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_52398\" data-quantity=\"1\" class=\"button product_type_variable\" data-product_id=\"52398\" data-product_sku=\"\" aria-label=\"Select options for &ldquo;Sia&rdquo;\" rel=\"nofollow\">Read more<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_52398\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n        <a class=\"l-product-slide__link\" href=\"https:\/\/ihg.bossdesign.com\/us\/product\/sia\"><\/a>\n    <\/div>\n<\/div><div >\n    <div\n            class=\"l-product-slide js-product-slides__slide\"\n            data-url=\"https:\/\/ihg.bossdesign.com\/us\/product\/amelia\"\n            data-media=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/09154321\/Amelia-Boss-Design-Lounge-Chair-feature.jpg\"\n            data-description=\"Amelia\"\n            aria-expanded=\"false\">\n        \n<div data-item_id=\"15875\" data-action=\"alg-wc-wl-toggle\" class=\"alg-wc-wl-btn add alg-wc-wl-thumb-btn alg-wc-wl-thumb-btn-abs alg-wc-wl-thumb-btn-loop\">\n\t<div class=\"alg-wc-wl-view-state alg-wc-wl-view-state-add\">\n\t\t<i class=\"l-product-slide__wishlist l-product-slide__wishlist--add\" aria-hidden=\"true\"><\/i>\n\t<\/div>\n\t<div class=\"alg-wc-wl-view-state alg-wc-wl-view-state-remove\">\n\t\t<i class=\"l-product-slide__wishlist l-product-slide__wishlist--remove\" aria-hidden=\"true\"><\/i>\n\t<\/div>\n\t<\/div><a href=\"https:\/\/ihg.bossdesign.com\/us\/projects-us\/workspace-us\/rocket-space\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <div class=\"l-product-slide__image\">\n            <img decoding=\"async\" src=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/09154321\/Amelia-Boss-Design-Lounge-Chair-feature.jpg\" alt=\"Amelia\" \/>\n        <\/div>\n        <div class=\"l-product-slide__info js-product-slides__slide-info\">\n            <div class=\"l-product-slide__info-inner\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/09154321\/Amelia-Boss-Design-Lounge-Chair-feature-300x225.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Amelia\" srcset=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/09154321\/Amelia-Boss-Design-Lounge-Chair-feature-300x225.jpg 300w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/09154321\/Amelia-Boss-Design-Lounge-Chair-feature-600x450.jpg 600w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/09154321\/Amelia-Boss-Design-Lounge-Chair-feature-1024x768.jpg 1024w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/09154321\/Amelia-Boss-Design-Lounge-Chair-feature-768x576.jpg 768w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/09154321\/Amelia-Boss-Design-Lounge-Chair-feature.jpg 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>                <h5>\n                    Amelia                <\/h5>\n                \n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&pound;<\/span>0.00<\/bdi><\/span><\/span>\n                <div\n                        hidden=\"hidden\"\n                        class=\"l-product-slide__call-to-action js-product-slides__call-to-action\">\n                    <p>\n                        <a href=\"https:\/\/ihg.bossdesign.com\/us\/product\/amelia\">View product<\/a>\n                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"25.052\" height=\"18.745\" viewBox=\"0 0 25.052 18.745\">\n                            <g id=\"Group_157\" data-name=\"Group 157\" transform=\"translate(0 0.354)\">\n                                <g id=\"Group_75\" data-name=\"Group 75\" transform=\"translate(0 0)\">\n                                    <g id=\"Group_74\" data-name=\"Group 74\">\n                                        <line id=\"Line_40\" data-name=\"Line 40\" x2=\"24.552\" transform=\"translate(0 9.019)\" fill=\"none\" stroke=\"#000\" stroke-linejoin=\"round\" stroke-width=\"1\"\/>\n                                        <path id=\"Path_41\" data-name=\"Path 41\" d=\"M4596.461,1377.324l9.019,9.019-9.019,9.019\" transform=\"translate(-4580.928 -1377.324)\" fill=\"none\" stroke=\"#000\" stroke-linejoin=\"round\" stroke-width=\"1\"\/>\n                                    <\/g>\n                                <\/g>\n                            <\/g>\n                        <\/svg>\n                    <\/p>\n                <\/div>\n            <\/div>\n        <\/div>\n        <div hidden=\"hidden\"\n             class=\"l-product-slide__pin js-product-slides__slide-pin\">\n            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"37.863\" height=\"37.857\" viewBox=\"0 0 37.863 37.857\">\n                <path id=\"Path_53\" data-name=\"Path 53\" d=\"M4264.124,1231.55a18.982,18.982,0,0,1,32.5-13.274,18.769,18.769,0,0,1,5.362,13.274,19.121,19.121,0,0,1-18.934,18.926,18.135,18.135,0,0,1-5.32-.814,21.083,21.083,0,0,0,1.032-1.846,31.1,31.1,0,0,0,1.478-4.733q.226-.96.671-2.591a4.786,4.786,0,0,0,1.774,1.629,7.737,7.737,0,0,0,7.022-.3,11.669,11.669,0,0,0,5.323-6.875,13.977,13.977,0,0,0-.334-9.057,10.672,10.672,0,0,0-5.951-6.027,16.44,16.44,0,0,0-10.5.333,11.8,11.8,0,0,0-7.1,6.469,15.056,15.056,0,0,0-.629,3.366,15.791,15.791,0,0,0,.11,3.253,6.4,6.4,0,0,0,1.11,2.847,5.675,5.675,0,0,0,2.363,1.922.624.624,0,0,0,.594,0c.2-.1.392-.49.587-1.181a3.6,3.6,0,0,0,.224-1.4c-.047-.1-.146-.273-.293-.519a7.205,7.205,0,0,1-1.034-5.285,9.281,9.281,0,0,1,2.292-4.693,10.273,10.273,0,0,1,6.394-2.664,8.447,8.447,0,0,1,6.246,2,7.983,7.983,0,0,1,1.81,3.918,11.963,11.963,0,0,1,0,4.4,13.258,13.258,0,0,1-1.44,3.958q-1.852,2.884-4.365,2.957a3.271,3.271,0,0,1-2.4-1.147,2.576,2.576,0,0,1-.553-2.477q.148-.812.889-3.18a16.954,16.954,0,0,0,.812-3.547q-.221-2.811-2.587-2.886a3.523,3.523,0,0,0-2.738,1.663,6.648,6.648,0,0,0-.965,3.29,8.762,8.762,0,0,0,.668,2.957q-.81,3.327-1.257,5.322c-.1.344-.37,1.406-.814,3.18a23.632,23.632,0,0,0-.739,4.067v2.072a19.491,19.491,0,0,1-8.278-7.061A18.309,18.309,0,0,1,4264.124,1231.55Z\" transform=\"translate(-4264.124 -1212.619)\"\/>\n            <\/svg>\n        <\/div>\n        <\/a><a href=\"https:\/\/ihg.bossdesign.com\/us\/product\/amelia\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_15875\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"15875\" data-product_sku=\"\" aria-label=\"Select options for &ldquo;Amelia&rdquo;\" rel=\"nofollow\">Select options<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_15875\" class=\"screen-reader-text\">\n\t\tThis product has multiple variants. The options may be chosen on the product page\t<\/span>\n        <a class=\"l-product-slide__link\" href=\"https:\/\/ihg.bossdesign.com\/us\/product\/amelia\"><\/a>\n    <\/div>\n<\/div><div >\n    <div\n            class=\"l-product-slide js-product-slides__slide\"\n            data-url=\"https:\/\/ihg.bossdesign.com\/us\/product\/brimm-2\"\n            data-media=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/06\/13175612\/Brimm-Product-Name-Boss-Design-Category--1-scaled.jpg\"\n            data-description=\"Brimm\"\n            aria-expanded=\"false\">\n        \n<div data-item_id=\"20059\" data-action=\"alg-wc-wl-toggle\" class=\"alg-wc-wl-btn add alg-wc-wl-thumb-btn alg-wc-wl-thumb-btn-abs alg-wc-wl-thumb-btn-loop\">\n\t<div class=\"alg-wc-wl-view-state alg-wc-wl-view-state-add\">\n\t\t<i class=\"l-product-slide__wishlist l-product-slide__wishlist--add\" aria-hidden=\"true\"><\/i>\n\t<\/div>\n\t<div class=\"alg-wc-wl-view-state alg-wc-wl-view-state-remove\">\n\t\t<i class=\"l-product-slide__wishlist l-product-slide__wishlist--remove\" aria-hidden=\"true\"><\/i>\n\t<\/div>\n\t<\/div><a href=\"https:\/\/ihg.bossdesign.com\/us\/projects-us\/workspace-us\/rocket-space\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <div class=\"l-product-slide__image\">\n            <img decoding=\"async\" src=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/06\/13175612\/Brimm-Product-Name-Boss-Design-Category--1-scaled.jpg\" alt=\"Brimm\" \/>\n        <\/div>\n        <div class=\"l-product-slide__info js-product-slides__slide-info\">\n            <div class=\"l-product-slide__info-inner\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/06\/13175612\/Brimm-Product-Name-Boss-Design-Category--1-scaled-300x225.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Brimm\" srcset=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/06\/13175612\/Brimm-Product-Name-Boss-Design-Category--1-scaled-300x225.jpg 300w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/06\/13175612\/Brimm-Product-Name-Boss-Design-Category--1-scaled-600x450.jpg 600w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/06\/13175612\/Brimm-Product-Name-Boss-Design-Category--1-1024x768.jpg 1024w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/06\/13175612\/Brimm-Product-Name-Boss-Design-Category--1-768x576.jpg 768w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/06\/13175612\/Brimm-Product-Name-Boss-Design-Category--1-1536x1152.jpg 1536w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/06\/13175612\/Brimm-Product-Name-Boss-Design-Category--1-2048x1536.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>                <h5>\n                    Brimm                <\/h5>\n                \n                <div\n                        hidden=\"hidden\"\n                        class=\"l-product-slide__call-to-action js-product-slides__call-to-action\">\n                    <p>\n                        <a href=\"https:\/\/ihg.bossdesign.com\/us\/product\/brimm-2\">View product<\/a>\n                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"25.052\" height=\"18.745\" viewBox=\"0 0 25.052 18.745\">\n                            <g id=\"Group_157\" data-name=\"Group 157\" transform=\"translate(0 0.354)\">\n                                <g id=\"Group_75\" data-name=\"Group 75\" transform=\"translate(0 0)\">\n                                    <g id=\"Group_74\" data-name=\"Group 74\">\n                                        <line id=\"Line_40\" data-name=\"Line 40\" x2=\"24.552\" transform=\"translate(0 9.019)\" fill=\"none\" stroke=\"#000\" stroke-linejoin=\"round\" stroke-width=\"1\"\/>\n                                        <path id=\"Path_41\" data-name=\"Path 41\" d=\"M4596.461,1377.324l9.019,9.019-9.019,9.019\" transform=\"translate(-4580.928 -1377.324)\" fill=\"none\" stroke=\"#000\" stroke-linejoin=\"round\" stroke-width=\"1\"\/>\n                                    <\/g>\n                                <\/g>\n                            <\/g>\n                        <\/svg>\n                    <\/p>\n                <\/div>\n            <\/div>\n        <\/div>\n        <div hidden=\"hidden\"\n             class=\"l-product-slide__pin js-product-slides__slide-pin\">\n            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"37.863\" height=\"37.857\" viewBox=\"0 0 37.863 37.857\">\n                <path id=\"Path_53\" data-name=\"Path 53\" d=\"M4264.124,1231.55a18.982,18.982,0,0,1,32.5-13.274,18.769,18.769,0,0,1,5.362,13.274,19.121,19.121,0,0,1-18.934,18.926,18.135,18.135,0,0,1-5.32-.814,21.083,21.083,0,0,0,1.032-1.846,31.1,31.1,0,0,0,1.478-4.733q.226-.96.671-2.591a4.786,4.786,0,0,0,1.774,1.629,7.737,7.737,0,0,0,7.022-.3,11.669,11.669,0,0,0,5.323-6.875,13.977,13.977,0,0,0-.334-9.057,10.672,10.672,0,0,0-5.951-6.027,16.44,16.44,0,0,0-10.5.333,11.8,11.8,0,0,0-7.1,6.469,15.056,15.056,0,0,0-.629,3.366,15.791,15.791,0,0,0,.11,3.253,6.4,6.4,0,0,0,1.11,2.847,5.675,5.675,0,0,0,2.363,1.922.624.624,0,0,0,.594,0c.2-.1.392-.49.587-1.181a3.6,3.6,0,0,0,.224-1.4c-.047-.1-.146-.273-.293-.519a7.205,7.205,0,0,1-1.034-5.285,9.281,9.281,0,0,1,2.292-4.693,10.273,10.273,0,0,1,6.394-2.664,8.447,8.447,0,0,1,6.246,2,7.983,7.983,0,0,1,1.81,3.918,11.963,11.963,0,0,1,0,4.4,13.258,13.258,0,0,1-1.44,3.958q-1.852,2.884-4.365,2.957a3.271,3.271,0,0,1-2.4-1.147,2.576,2.576,0,0,1-.553-2.477q.148-.812.889-3.18a16.954,16.954,0,0,0,.812-3.547q-.221-2.811-2.587-2.886a3.523,3.523,0,0,0-2.738,1.663,6.648,6.648,0,0,0-.965,3.29,8.762,8.762,0,0,0,.668,2.957q-.81,3.327-1.257,5.322c-.1.344-.37,1.406-.814,3.18a23.632,23.632,0,0,0-.739,4.067v2.072a19.491,19.491,0,0,1-8.278-7.061A18.309,18.309,0,0,1,4264.124,1231.55Z\" transform=\"translate(-4264.124 -1212.619)\"\/>\n            <\/svg>\n        <\/div>\n        <\/a><a href=\"https:\/\/ihg.bossdesign.com\/us\/product\/brimm-2\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_20059\" data-quantity=\"1\" class=\"button product_type_variable\" data-product_id=\"20059\" data-product_sku=\"BRI\/1*\" aria-label=\"Select options for &ldquo;Brimm&rdquo;\" rel=\"nofollow\">Read more<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_20059\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n        <a class=\"l-product-slide__link\" href=\"https:\/\/ihg.bossdesign.com\/us\/product\/brimm-2\"><\/a>\n    <\/div>\n<\/div><div >\n    <div\n            class=\"l-product-slide js-product-slides__slide\"\n            data-url=\"https:\/\/ihg.bossdesign.com\/us\/product\/toto\"\n            data-media=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/06\/25170309\/Toto-Boss-Design-Lounge-Chair-.jpg\"\n            data-description=\"Toto\"\n            aria-expanded=\"false\">\n        \n<div data-item_id=\"16811\" data-action=\"alg-wc-wl-toggle\" class=\"alg-wc-wl-btn add alg-wc-wl-thumb-btn alg-wc-wl-thumb-btn-abs alg-wc-wl-thumb-btn-loop\">\n\t<div class=\"alg-wc-wl-view-state alg-wc-wl-view-state-add\">\n\t\t<i class=\"l-product-slide__wishlist l-product-slide__wishlist--add\" aria-hidden=\"true\"><\/i>\n\t<\/div>\n\t<div class=\"alg-wc-wl-view-state alg-wc-wl-view-state-remove\">\n\t\t<i class=\"l-product-slide__wishlist l-product-slide__wishlist--remove\" aria-hidden=\"true\"><\/i>\n\t<\/div>\n\t<\/div><a href=\"https:\/\/ihg.bossdesign.com\/us\/projects-us\/workspace-us\/rocket-space\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <div class=\"l-product-slide__image\">\n            <img decoding=\"async\" src=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/06\/25170309\/Toto-Boss-Design-Lounge-Chair-.jpg\" alt=\"Toto\" \/>\n        <\/div>\n        <div class=\"l-product-slide__info js-product-slides__slide-info\">\n            <div class=\"l-product-slide__info-inner\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/06\/25170309\/Toto-Boss-Design-Lounge-Chair--300x225.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Toto\" srcset=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/06\/25170309\/Toto-Boss-Design-Lounge-Chair--300x225.jpg 300w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/06\/25170309\/Toto-Boss-Design-Lounge-Chair--600x450.jpg 600w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/06\/25170309\/Toto-Boss-Design-Lounge-Chair--1024x768.jpg 1024w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/06\/25170309\/Toto-Boss-Design-Lounge-Chair--768x576.jpg 768w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/06\/25170309\/Toto-Boss-Design-Lounge-Chair-.jpg 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>                <h5>\n                    Toto                <\/h5>\n                \n                <div\n                        hidden=\"hidden\"\n                        class=\"l-product-slide__call-to-action js-product-slides__call-to-action\">\n                    <p>\n                        <a href=\"https:\/\/ihg.bossdesign.com\/us\/product\/toto\">View product<\/a>\n                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"25.052\" height=\"18.745\" viewBox=\"0 0 25.052 18.745\">\n                            <g id=\"Group_157\" data-name=\"Group 157\" transform=\"translate(0 0.354)\">\n                                <g id=\"Group_75\" data-name=\"Group 75\" transform=\"translate(0 0)\">\n                                    <g id=\"Group_74\" data-name=\"Group 74\">\n                                        <line id=\"Line_40\" data-name=\"Line 40\" x2=\"24.552\" transform=\"translate(0 9.019)\" fill=\"none\" stroke=\"#000\" stroke-linejoin=\"round\" stroke-width=\"1\"\/>\n                                        <path id=\"Path_41\" data-name=\"Path 41\" d=\"M4596.461,1377.324l9.019,9.019-9.019,9.019\" transform=\"translate(-4580.928 -1377.324)\" fill=\"none\" stroke=\"#000\" stroke-linejoin=\"round\" stroke-width=\"1\"\/>\n                                    <\/g>\n                                <\/g>\n                            <\/g>\n                        <\/svg>\n                    <\/p>\n                <\/div>\n            <\/div>\n        <\/div>\n        <div hidden=\"hidden\"\n             class=\"l-product-slide__pin js-product-slides__slide-pin\">\n            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"37.863\" height=\"37.857\" viewBox=\"0 0 37.863 37.857\">\n                <path id=\"Path_53\" data-name=\"Path 53\" d=\"M4264.124,1231.55a18.982,18.982,0,0,1,32.5-13.274,18.769,18.769,0,0,1,5.362,13.274,19.121,19.121,0,0,1-18.934,18.926,18.135,18.135,0,0,1-5.32-.814,21.083,21.083,0,0,0,1.032-1.846,31.1,31.1,0,0,0,1.478-4.733q.226-.96.671-2.591a4.786,4.786,0,0,0,1.774,1.629,7.737,7.737,0,0,0,7.022-.3,11.669,11.669,0,0,0,5.323-6.875,13.977,13.977,0,0,0-.334-9.057,10.672,10.672,0,0,0-5.951-6.027,16.44,16.44,0,0,0-10.5.333,11.8,11.8,0,0,0-7.1,6.469,15.056,15.056,0,0,0-.629,3.366,15.791,15.791,0,0,0,.11,3.253,6.4,6.4,0,0,0,1.11,2.847,5.675,5.675,0,0,0,2.363,1.922.624.624,0,0,0,.594,0c.2-.1.392-.49.587-1.181a3.6,3.6,0,0,0,.224-1.4c-.047-.1-.146-.273-.293-.519a7.205,7.205,0,0,1-1.034-5.285,9.281,9.281,0,0,1,2.292-4.693,10.273,10.273,0,0,1,6.394-2.664,8.447,8.447,0,0,1,6.246,2,7.983,7.983,0,0,1,1.81,3.918,11.963,11.963,0,0,1,0,4.4,13.258,13.258,0,0,1-1.44,3.958q-1.852,2.884-4.365,2.957a3.271,3.271,0,0,1-2.4-1.147,2.576,2.576,0,0,1-.553-2.477q.148-.812.889-3.18a16.954,16.954,0,0,0,.812-3.547q-.221-2.811-2.587-2.886a3.523,3.523,0,0,0-2.738,1.663,6.648,6.648,0,0,0-.965,3.29,8.762,8.762,0,0,0,.668,2.957q-.81,3.327-1.257,5.322c-.1.344-.37,1.406-.814,3.18a23.632,23.632,0,0,0-.739,4.067v2.072a19.491,19.491,0,0,1-8.278-7.061A18.309,18.309,0,0,1,4264.124,1231.55Z\" transform=\"translate(-4264.124 -1212.619)\"\/>\n            <\/svg>\n        <\/div>\n        <\/a><a href=\"https:\/\/ihg.bossdesign.com\/us\/product\/toto\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_16811\" data-quantity=\"1\" class=\"button product_type_variable\" data-product_id=\"16811\" data-product_sku=\"\" aria-label=\"Select options for &ldquo;Toto&rdquo;\" rel=\"nofollow\">Read more<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_16811\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n        <a class=\"l-product-slide__link\" href=\"https:\/\/ihg.bossdesign.com\/us\/product\/toto\"><\/a>\n    <\/div>\n<\/div>    <\/div>\n    <div class=\"c-carousel__pagination js-carousel__pagination\">\n    <span class=\"js-carousel__pagination--current\">1<\/span>\/<span class=\"js-carousel__pagination--total\">12<\/span>\n<\/div>\n<ul class=\"c-carousel__controls js-carousel__controls\">\n    <li class=\"c-carousel__control c-carousel-controls c-carousel-controls__previous js-carousel__control--previous\">\n        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"9.849\" height=\"17.699\" viewBox=\"0 0 9.849 17.699\">\n    <path id=\"previous-arrow\" data-name=\"back-chevron\" d=\"M0,16.992,8.789,8.2.585,0\" transform=\"translate(9.496 17.346) rotate(180)\" fill=\"none\" stroke=\"#000\" stroke-miterlimit=\"10\" stroke-width=\"1\"\/>\n<\/svg>        <span>Previous<\/span>\n    <\/li>\n    <li class=\"c-carousel__control c-carousel-controls c-carousel-controls__next js-carousel__control--next\">\n        <span>Next<\/span>\n        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"9.849\" height=\"17.699\" viewBox=\"0 0 9.849 17.699\">\n    <path id=\"next-arrow\" data-name=\"forward-chevron\" d=\"M4777.469,1010.609l8.789-8.789-8.2-8.2\" transform=\"translate(-4777.115 -993.263)\" fill=\"none\" stroke=\"#000\" stroke-miterlimit=\"10\" stroke-width=\"1\"\/>\n<\/svg>    <\/li>\n<\/ul><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Overview Rocket Space is a flexible, hassle-free, professional place to work from. Spaces have been created to stimulate and build a strong company culture. The managed office space allows people to focus on activities that benefit their company. It was an essential part of the brief to create multiple spaces for brainstorming, fast meetings, large [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":15103,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[174],"tags":[],"class_list":["post-17061","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-workspace-us"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rocket Space - Boss Design x IHG<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ihg.bossdesign.com\/us\/projects-us\/workspace-us\/rocket-space\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rocket Space - Boss Design x IHG\" \/>\n<meta property=\"og:description\" content=\"Overview Rocket Space is a flexible, hassle-free, professional place to work from. Spaces have been created to stimulate and build a strong company culture. The managed office space allows people to focus on activities that benefit their company. It was an essential part of the brief to create multiple spaces for brainstorming, fast meetings, large [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ihg.bossdesign.com\/us\/projects-us\/workspace-us\/rocket-space\" \/>\n<meta property=\"og:site_name\" content=\"Boss Design x IHG\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-14T15:58:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-20T09:35:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/05\/06213101\/RocketSpace-Case-Study-Boss-Design-.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dan Akers\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dan Akers\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ihg.bossdesign.com\\\/us\\\/projects-us\\\/workspace-us\\\/rocket-space#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ihg.bossdesign.com\\\/us\\\/projects-us\\\/workspace-us\\\/rocket-space\"},\"author\":{\"name\":\"Dan Akers\",\"@id\":\"https:\\\/\\\/ihg.bossdesign.com\\\/us#\\\/schema\\\/person\\\/81473d055712ba80997093dfc9838046\"},\"headline\":\"Rocket Space\",\"datePublished\":\"2021-12-14T15:58:21+00:00\",\"dateModified\":\"2022-06-20T09:35:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ihg.bossdesign.com\\\/us\\\/projects-us\\\/workspace-us\\\/rocket-space\"},\"wordCount\":270,\"publisher\":{\"@id\":\"https:\\\/\\\/ihg.bossdesign.com\\\/us#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/ihg.bossdesign.com\\\/us\\\/projects-us\\\/workspace-us\\\/rocket-space#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/boss-design-assets.s3.eu-west-2.amazonaws.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/06213101\\\/RocketSpace-Case-Study-Boss-Design-.jpg\",\"articleSection\":[\"Workspace\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ihg.bossdesign.com\\\/us\\\/projects-us\\\/workspace-us\\\/rocket-space\",\"url\":\"https:\\\/\\\/ihg.bossdesign.com\\\/us\\\/projects-us\\\/workspace-us\\\/rocket-space\",\"name\":\"Rocket Space - Boss Design x IHG\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ihg.bossdesign.com\\\/us#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ihg.bossdesign.com\\\/us\\\/projects-us\\\/workspace-us\\\/rocket-space#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ihg.bossdesign.com\\\/us\\\/projects-us\\\/workspace-us\\\/rocket-space#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/boss-design-assets.s3.eu-west-2.amazonaws.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/06213101\\\/RocketSpace-Case-Study-Boss-Design-.jpg\",\"datePublished\":\"2021-12-14T15:58:21+00:00\",\"dateModified\":\"2022-06-20T09:35:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ihg.bossdesign.com\\\/us\\\/projects-us\\\/workspace-us\\\/rocket-space#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ihg.bossdesign.com\\\/us\\\/projects-us\\\/workspace-us\\\/rocket-space\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/ihg.bossdesign.com\\\/us\\\/projects-us\\\/workspace-us\\\/rocket-space#primaryimage\",\"url\":\"https:\\\/\\\/boss-design-assets.s3.eu-west-2.amazonaws.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/06213101\\\/RocketSpace-Case-Study-Boss-Design-.jpg\",\"contentUrl\":\"https:\\\/\\\/boss-design-assets.s3.eu-west-2.amazonaws.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/06213101\\\/RocketSpace-Case-Study-Boss-Design-.jpg\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ihg.bossdesign.com\\\/us\\\/projects-us\\\/workspace-us\\\/rocket-space#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ihg.bossdesign.com\\\/us\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rocket Space\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ihg.bossdesign.com\\\/us#website\",\"url\":\"https:\\\/\\\/ihg.bossdesign.com\\\/us\",\"name\":\"Boss Design x IHG\",\"description\":\"Boss Design - leading furniture designer and manufacturer\",\"publisher\":{\"@id\":\"https:\\\/\\\/ihg.bossdesign.com\\\/us#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ihg.bossdesign.com\\\/us?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ihg.bossdesign.com\\\/us#organization\",\"name\":\"Boss Design x IHG\",\"url\":\"https:\\\/\\\/ihg.bossdesign.com\\\/us\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/ihg.bossdesign.com\\\/us#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/boss-design-assets.s3.eu-west-2.amazonaws.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/29105425\\\/Boss-x-IHG-Logo-Header3.png\",\"contentUrl\":\"https:\\\/\\\/boss-design-assets.s3.eu-west-2.amazonaws.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/29105425\\\/Boss-x-IHG-Logo-Header3.png\",\"width\":900,\"height\":231,\"caption\":\"Boss Design x IHG\"},\"image\":{\"@id\":\"https:\\\/\\\/ihg.bossdesign.com\\\/us#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ihg.bossdesign.com\\\/us#\\\/schema\\\/person\\\/81473d055712ba80997093dfc9838046\",\"name\":\"Dan Akers\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2711dadc02da0116b8ada84e88a7dd62bb1c5c1f45cd8b2b2e3f04edf5539c8b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2711dadc02da0116b8ada84e88a7dd62bb1c5c1f45cd8b2b2e3f04edf5539c8b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2711dadc02da0116b8ada84e88a7dd62bb1c5c1f45cd8b2b2e3f04edf5539c8b?s=96&d=mm&r=g\",\"caption\":\"Dan Akers\"},\"sameAs\":[\"https:\\\/\\\/goldtopcollective.com\"],\"url\":\"https:\\\/\\\/ihg.bossdesign.com\\\/us\\\/author\\\/boss2021\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rocket Space - Boss Design x IHG","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ihg.bossdesign.com\/us\/projects-us\/workspace-us\/rocket-space","og_locale":"en_US","og_type":"article","og_title":"Rocket Space - Boss Design x IHG","og_description":"Overview Rocket Space is a flexible, hassle-free, professional place to work from. Spaces have been created to stimulate and build a strong company culture. The managed office space allows people to focus on activities that benefit their company. It was an essential part of the brief to create multiple spaces for brainstorming, fast meetings, large [&hellip;]","og_url":"https:\/\/ihg.bossdesign.com\/us\/projects-us\/workspace-us\/rocket-space","og_site_name":"Boss Design x IHG","article_published_time":"2021-12-14T15:58:21+00:00","article_modified_time":"2022-06-20T09:35:08+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/05\/06213101\/RocketSpace-Case-Study-Boss-Design-.jpg","type":"image\/jpeg"}],"author":"Dan Akers","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Dan Akers","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ihg.bossdesign.com\/us\/projects-us\/workspace-us\/rocket-space#article","isPartOf":{"@id":"https:\/\/ihg.bossdesign.com\/us\/projects-us\/workspace-us\/rocket-space"},"author":{"name":"Dan Akers","@id":"https:\/\/ihg.bossdesign.com\/us#\/schema\/person\/81473d055712ba80997093dfc9838046"},"headline":"Rocket Space","datePublished":"2021-12-14T15:58:21+00:00","dateModified":"2022-06-20T09:35:08+00:00","mainEntityOfPage":{"@id":"https:\/\/ihg.bossdesign.com\/us\/projects-us\/workspace-us\/rocket-space"},"wordCount":270,"publisher":{"@id":"https:\/\/ihg.bossdesign.com\/us#organization"},"image":{"@id":"https:\/\/ihg.bossdesign.com\/us\/projects-us\/workspace-us\/rocket-space#primaryimage"},"thumbnailUrl":"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/05\/06213101\/RocketSpace-Case-Study-Boss-Design-.jpg","articleSection":["Workspace"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/ihg.bossdesign.com\/us\/projects-us\/workspace-us\/rocket-space","url":"https:\/\/ihg.bossdesign.com\/us\/projects-us\/workspace-us\/rocket-space","name":"Rocket Space - Boss Design x IHG","isPartOf":{"@id":"https:\/\/ihg.bossdesign.com\/us#website"},"primaryImageOfPage":{"@id":"https:\/\/ihg.bossdesign.com\/us\/projects-us\/workspace-us\/rocket-space#primaryimage"},"image":{"@id":"https:\/\/ihg.bossdesign.com\/us\/projects-us\/workspace-us\/rocket-space#primaryimage"},"thumbnailUrl":"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/05\/06213101\/RocketSpace-Case-Study-Boss-Design-.jpg","datePublished":"2021-12-14T15:58:21+00:00","dateModified":"2022-06-20T09:35:08+00:00","breadcrumb":{"@id":"https:\/\/ihg.bossdesign.com\/us\/projects-us\/workspace-us\/rocket-space#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ihg.bossdesign.com\/us\/projects-us\/workspace-us\/rocket-space"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ihg.bossdesign.com\/us\/projects-us\/workspace-us\/rocket-space#primaryimage","url":"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/05\/06213101\/RocketSpace-Case-Study-Boss-Design-.jpg","contentUrl":"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/05\/06213101\/RocketSpace-Case-Study-Boss-Design-.jpg","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/ihg.bossdesign.com\/us\/projects-us\/workspace-us\/rocket-space#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ihg.bossdesign.com\/us"},{"@type":"ListItem","position":2,"name":"Rocket Space"}]},{"@type":"WebSite","@id":"https:\/\/ihg.bossdesign.com\/us#website","url":"https:\/\/ihg.bossdesign.com\/us","name":"Boss Design x IHG","description":"Boss Design - leading furniture designer and manufacturer","publisher":{"@id":"https:\/\/ihg.bossdesign.com\/us#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ihg.bossdesign.com\/us?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/ihg.bossdesign.com\/us#organization","name":"Boss Design x IHG","url":"https:\/\/ihg.bossdesign.com\/us","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ihg.bossdesign.com\/us#\/schema\/logo\/image\/","url":"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/04\/29105425\/Boss-x-IHG-Logo-Header3.png","contentUrl":"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/04\/29105425\/Boss-x-IHG-Logo-Header3.png","width":900,"height":231,"caption":"Boss Design x IHG"},"image":{"@id":"https:\/\/ihg.bossdesign.com\/us#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ihg.bossdesign.com\/us#\/schema\/person\/81473d055712ba80997093dfc9838046","name":"Dan Akers","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/2711dadc02da0116b8ada84e88a7dd62bb1c5c1f45cd8b2b2e3f04edf5539c8b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2711dadc02da0116b8ada84e88a7dd62bb1c5c1f45cd8b2b2e3f04edf5539c8b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2711dadc02da0116b8ada84e88a7dd62bb1c5c1f45cd8b2b2e3f04edf5539c8b?s=96&d=mm&r=g","caption":"Dan Akers"},"sameAs":["https:\/\/goldtopcollective.com"],"url":"https:\/\/ihg.bossdesign.com\/us\/author\/boss2021"}]}},"_links":{"self":[{"href":"https:\/\/ihg.bossdesign.com\/us\/wp-json\/wp\/v2\/posts\/17061","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ihg.bossdesign.com\/us\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ihg.bossdesign.com\/us\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ihg.bossdesign.com\/us\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ihg.bossdesign.com\/us\/wp-json\/wp\/v2\/comments?post=17061"}],"version-history":[{"count":0,"href":"https:\/\/ihg.bossdesign.com\/us\/wp-json\/wp\/v2\/posts\/17061\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ihg.bossdesign.com\/us\/wp-json\/wp\/v2\/media\/15103"}],"wp:attachment":[{"href":"https:\/\/ihg.bossdesign.com\/us\/wp-json\/wp\/v2\/media?parent=17061"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ihg.bossdesign.com\/us\/wp-json\/wp\/v2\/categories?post=17061"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ihg.bossdesign.com\/us\/wp-json\/wp\/v2\/tags?post=17061"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}