{"id":28307,"date":"2022-06-20T10:24:54","date_gmt":"2022-06-20T10:24:54","guid":{"rendered":"https:\/\/ihgboss.startlingstaging.com\/non-classifiee\/financial-institution"},"modified":"2022-06-20T10:24:55","modified_gmt":"2022-06-20T10:24:55","slug":"financial-institution","status":"publish","type":"post","link":"https:\/\/ihg.bossdesign.com\/fr\/projects-fr\/corporate-fr\/financial-institution","title":{"rendered":"Financial Institution"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"28307\" class=\"elementor elementor-28307\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-26e10052 animated-slow elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"26e10052\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7f32890d\" data-id=\"7f32890d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-78f51f73 elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"78f51f73\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Financial Institution<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-101c4921 elementor-widget elementor-widget-text-editor\" data-id=\"101c4921\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Oman, Middle East<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a217b4 elementor-widget elementor-widget-text-editor\" data-id=\"4a217b4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h5>Bringing luxury and elegance to the workplace, this high profile global financial institution specified the Boss Design classic, <a href=\"https:\/\/https:\/\/ihg.bossdesign.com\/product-list\/kruze\/\">Kruze<\/a>, to sit around bespoke boardroom tables.<\/h5>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9a780ba elementor-widget elementor-widget-text-editor\" data-id=\"9a780ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Combining traditional and antique artworks, with a modern finish spec on the furniture, brings a level of sophistication and opulence not usually associated within the workplace arena.<\/p><p>Upholstered in a luxurious velvet, <a href=\"https:\/\/https:\/\/ihg.bossdesign.com\/product-list\/manta\/\">Manta<\/a> sofas and armchairs grace the welcome area.<\/p><p><a href=\"https:\/\/https:\/\/ihg.bossdesign.com\/product-list\/toto\/\">Toto<\/a> armchairs on a painted sled base were chosen for various formal meeting spaces.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1ee2c4c6\" data-id=\"1ee2c4c6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e14ed8c elementor-widget elementor-widget-image\" data-id=\"e14ed8c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"900\" src=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121523\/london_financial_institution_4-910x1024.jpg\" class=\"attachment-large size-large wp-image-15422\" alt=\"\" srcset=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121523\/london_financial_institution_4-910x1024.jpg 910w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121523\/london_financial_institution_4-600x675.jpg 600w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121523\/london_financial_institution_4-267x300.jpg 267w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121523\/london_financial_institution_4-768x864.jpg 768w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121523\/london_financial_institution_4.jpg 960w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c155140 animated-slow elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"c155140\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ab436bb\" data-id=\"ab436bb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5596307 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5596307\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-940c82d\" data-id=\"940c82d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-13fde7a elementor-widget elementor-widget-image\" data-id=\"13fde7a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"900\" src=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121528\/london_financial_institution_6-910x1024.jpg\" class=\"attachment-large size-large wp-image-15428\" alt=\"\" srcset=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121528\/london_financial_institution_6-910x1024.jpg 910w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121528\/london_financial_institution_6-600x675.jpg 600w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121528\/london_financial_institution_6-267x300.jpg 267w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121528\/london_financial_institution_6-768x864.jpg 768w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121528\/london_financial_institution_6.jpg 960w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d6c6ce2\" data-id=\"d6c6ce2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-27806de elementor-widget elementor-widget-text-editor\" data-id=\"27806de\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4><strong>Featured Products<\/strong><\/h4><p> <\/p><p><b style=\"font-size: 1rem;\">Kruze<\/b><span style=\"font-size: 16px;\"><b><br><\/b><\/span>Meeting Chairs<\/p><p><strong>Manta<\/strong><br>Armchair &amp; Sofa<\/p><p><strong>Toto<\/strong> <br>Meeting Chair<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1b294ee animated-slow elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"1b294ee\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:100}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b18020b\" data-id=\"b18020b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5373e4a elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"5373e4a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d4effd6 elementor-widget elementor-widget-image\" data-id=\"d4effd6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121521\/london_financial_institution_3.jpg\" class=\"attachment-full size-full wp-image-15419\" alt=\"\" srcset=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121521\/london_financial_institution_3.jpg 1920w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121521\/london_financial_institution_3-600x338.jpg 600w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121521\/london_financial_institution_3-300x169.jpg 300w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121521\/london_financial_institution_3-1024x576.jpg 1024w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121521\/london_financial_institution_3-768x432.jpg 768w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121521\/london_financial_institution_3-1536x864.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-76d0434 elementor-widget elementor-widget-spacer\" data-id=\"76d0434\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df2bf7d elementor-widget elementor-widget-image\" data-id=\"df2bf7d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121551\/london_financial_institution_15.jpg\" class=\"attachment-full size-full wp-image-15455\" alt=\"\" srcset=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121551\/london_financial_institution_15.jpg 1920w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121551\/london_financial_institution_15-600x338.jpg 600w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121551\/london_financial_institution_15-300x169.jpg 300w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121551\/london_financial_institution_15-1024x576.jpg 1024w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121551\/london_financial_institution_15-768x432.jpg 768w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121551\/london_financial_institution_15-1536x864.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-30b098c elementor-widget elementor-widget-spacer\" data-id=\"30b098c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4059331 elementor-widget elementor-widget-image\" data-id=\"4059331\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121545\/london_financial_institution_13.jpg\" class=\"attachment-full size-full wp-image-15449\" alt=\"\" srcset=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121545\/london_financial_institution_13.jpg 1920w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121545\/london_financial_institution_13-600x338.jpg 600w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121545\/london_financial_institution_13-300x169.jpg 300w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121545\/london_financial_institution_13-1024x576.jpg 1024w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121545\/london_financial_institution_13-768x432.jpg 768w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121545\/london_financial_institution_13-1536x864.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7f50b3d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7f50b3d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-67a9847\" data-id=\"67a9847\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cde231b elementor-widget elementor-widget-image\" data-id=\"cde231b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"900\" src=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121537\/london_financial_institution_10-910x1024.jpg\" class=\"attachment-large size-large wp-image-15440\" alt=\"\" srcset=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121537\/london_financial_institution_10-910x1024.jpg 910w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121537\/london_financial_institution_10-600x675.jpg 600w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121537\/london_financial_institution_10-267x300.jpg 267w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121537\/london_financial_institution_10-768x864.jpg 768w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121537\/london_financial_institution_10.jpg 960w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e3335eb elementor-widget elementor-widget-spacer\" data-id=\"e3335eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-07968a3\" data-id=\"07968a3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f718306 elementor-widget elementor-widget-image\" data-id=\"f718306\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"900\" src=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121535\/london_financial_institution_9-910x1024.jpg\" class=\"attachment-large size-large wp-image-15437\" alt=\"\" srcset=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121535\/london_financial_institution_9-910x1024.jpg 910w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121535\/london_financial_institution_9-600x675.jpg 600w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121535\/london_financial_institution_9-267x300.jpg 267w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121535\/london_financial_institution_9-768x864.jpg 768w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121535\/london_financial_institution_9.jpg 960w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-289c124 elementor-widget elementor-widget-spacer\" data-id=\"289c124\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-91c5213 elementor-widget elementor-widget-image\" data-id=\"91c5213\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121554\/london_financial_institution_16.jpg\" class=\"attachment-full size-full wp-image-15458\" alt=\"\" srcset=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121554\/london_financial_institution_16.jpg 1920w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121554\/london_financial_institution_16-600x338.jpg 600w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121554\/london_financial_institution_16-300x169.jpg 300w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121554\/london_financial_institution_16-1024x576.jpg 1024w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121554\/london_financial_institution_16-768x432.jpg 768w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121554\/london_financial_institution_16-1536x864.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b17ad05 elementor-widget elementor-widget-spacer\" data-id=\"b17ad05\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2b856dc elementor-widget elementor-widget-image\" data-id=\"2b856dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121557\/london_financial_institution_17.jpg\" class=\"attachment-full size-full wp-image-15461\" alt=\"\" srcset=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121557\/london_financial_institution_17.jpg 1920w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121557\/london_financial_institution_17-600x338.jpg 600w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121557\/london_financial_institution_17-300x169.jpg 300w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121557\/london_financial_institution_17-1024x576.jpg 1024w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121557\/london_financial_institution_17-768x432.jpg 768w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121557\/london_financial_institution_17-1536x864.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f674623 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f674623\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9a367e3\" data-id=\"9a367e3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-937b6fe elementor-widget elementor-widget-image\" data-id=\"937b6fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"900\" src=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121526\/london_financial_institution_5-910x1024.jpg\" class=\"attachment-large size-large wp-image-15425\" alt=\"\" srcset=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121526\/london_financial_institution_5-910x1024.jpg 910w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121526\/london_financial_institution_5-600x675.jpg 600w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121526\/london_financial_institution_5-267x300.jpg 267w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121526\/london_financial_institution_5-768x864.jpg 768w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121526\/london_financial_institution_5.jpg 960w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9a772ca elementor-widget elementor-widget-spacer\" data-id=\"9a772ca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a6262d9\" data-id=\"a6262d9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b45f931 elementor-widget elementor-widget-image\" data-id=\"b45f931\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"900\" src=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121528\/london_financial_institution_6-910x1024.jpg\" class=\"attachment-large size-large wp-image-15428\" alt=\"\" srcset=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121528\/london_financial_institution_6-910x1024.jpg 910w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121528\/london_financial_institution_6-600x675.jpg 600w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121528\/london_financial_institution_6-267x300.jpg 267w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121528\/london_financial_institution_6-768x864.jpg 768w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121528\/london_financial_institution_6.jpg 960w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-131d2d1 elementor-widget elementor-widget-spacer\" data-id=\"131d2d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-bd485f2 elementor-widget elementor-widget-image\" data-id=\"bd485f2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121542\/london_financial_institution_12.jpg\" class=\"attachment-full size-full wp-image-15446\" alt=\"\" srcset=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121542\/london_financial_institution_12.jpg 1920w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121542\/london_financial_institution_12-600x338.jpg 600w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121542\/london_financial_institution_12-300x169.jpg 300w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121542\/london_financial_institution_12-1024x576.jpg 1024w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121542\/london_financial_institution_12-768x432.jpg 768w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121542\/london_financial_institution_12-1536x864.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e191eef elementor-widget elementor-widget-spacer\" data-id=\"e191eef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9337792 elementor-widget elementor-widget-image\" data-id=\"9337792\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121548\/london_financial_institution_14.jpg\" class=\"attachment-full size-full wp-image-15452\" alt=\"\" srcset=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121548\/london_financial_institution_14.jpg 1920w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121548\/london_financial_institution_14-600x338.jpg 600w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121548\/london_financial_institution_14-300x169.jpg 300w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121548\/london_financial_institution_14-1024x576.jpg 1024w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121548\/london_financial_institution_14-768x432.jpg 768w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/21121548\/london_financial_institution_14-1536x864.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-92488e2 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"92488e2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-743e40c animated-slow elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"743e40c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-27417b1f\" data-id=\"27417b1f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-363c23e7 elementor-widget elementor-widget-heading\" data-id=\"363c23e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Featured Products<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6a4d8a42 animated-slow elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"6a4d8a42\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3dfecf5\" data-id=\"3dfecf5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-69c6e1c2 elementor-widget elementor-widget-bdw_product_slider\" data-id=\"69c6e1c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"bdw_product_slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"l-product-slider l-product-slider--loading js-product-slides\">\n    <div class=\"js-product-slides--loading js-product-slides__carousel\">\n        <div >\n    <div\n            class=\"l-product-slide js-product-slides__slide\"\n            data-url=\"https:\/\/ihg.bossdesign.com\/fr\/produit\/kruze\"\n            data-media=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/06\/30144451\/Kruze-Boss-Design-Chair-.jpg\"\n            data-description=\"Kruze\"\n            aria-expanded=\"false\">\n        \n<div data-item_id=\"24636\" data-action=\"alg-wc-wl-toggle\" class=\"alg-wc-wl-btn add alg-wc-wl-thumb-btn alg-wc-wl-thumb-btn-abs alg-wc-wl-thumb-btn-loop\">\n\t<div class=\"alg-wc-wl-view-state alg-wc-wl-view-state-add\">\n\t\t<i class=\"l-product-slide__wishlist l-product-slide__wishlist--add\" aria-hidden=\"true\"><\/i>\n\t<\/div>\n\t<div class=\"alg-wc-wl-view-state alg-wc-wl-view-state-remove\">\n\t\t<i class=\"l-product-slide__wishlist l-product-slide__wishlist--remove\" aria-hidden=\"true\"><\/i>\n\t<\/div>\n\t<\/div><a href=\"https:\/\/ihg.bossdesign.com\/fr\/projects-fr\/corporate-fr\/financial-institution\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <div class=\"l-product-slide__image\">\n            <img decoding=\"async\" src=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/06\/30144451\/Kruze-Boss-Design-Chair-.jpg\" alt=\"Kruze\" \/>\n        <\/div>\n        <div class=\"l-product-slide__info js-product-slides__slide-info\">\n            <div class=\"l-product-slide__info-inner\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/06\/30144451\/Kruze-Boss-Design-Chair--300x225.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Kruze\" srcset=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/06\/30144451\/Kruze-Boss-Design-Chair--300x225.jpg 300w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/06\/30144451\/Kruze-Boss-Design-Chair--1024x768.jpg 1024w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/06\/30144451\/Kruze-Boss-Design-Chair--768x576.jpg 768w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/06\/30144451\/Kruze-Boss-Design-Chair--600x450.jpg 600w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/06\/30144451\/Kruze-Boss-Design-Chair-.jpg 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>                <h5>\n                    Kruze                <\/h5>\n                \n                <div\n                        hidden=\"hidden\"\n                        class=\"l-product-slide__call-to-action js-product-slides__call-to-action\">\n                    <p>\n                        <a href=\"https:\/\/ihg.bossdesign.com\/fr\/produit\/kruze\">View product<\/a>\n                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"25.052\" height=\"18.745\" viewBox=\"0 0 25.052 18.745\">\n                            <g id=\"Group_157\" data-name=\"Group 157\" transform=\"translate(0 0.354)\">\n                                <g id=\"Group_75\" data-name=\"Group 75\" transform=\"translate(0 0)\">\n                                    <g id=\"Group_74\" data-name=\"Group 74\">\n                                        <line id=\"Line_40\" data-name=\"Line 40\" x2=\"24.552\" transform=\"translate(0 9.019)\" fill=\"none\" stroke=\"#000\" stroke-linejoin=\"round\" stroke-width=\"1\"\/>\n                                        <path id=\"Path_41\" data-name=\"Path 41\" d=\"M4596.461,1377.324l9.019,9.019-9.019,9.019\" transform=\"translate(-4580.928 -1377.324)\" fill=\"none\" stroke=\"#000\" stroke-linejoin=\"round\" stroke-width=\"1\"\/>\n                                    <\/g>\n                                <\/g>\n                            <\/g>\n                        <\/svg>\n                    <\/p>\n                <\/div>\n            <\/div>\n        <\/div>\n        <div hidden=\"hidden\"\n             class=\"l-product-slide__pin js-product-slides__slide-pin\">\n            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"37.863\" height=\"37.857\" viewBox=\"0 0 37.863 37.857\">\n                <path id=\"Path_53\" data-name=\"Path 53\" d=\"M4264.124,1231.55a18.982,18.982,0,0,1,32.5-13.274,18.769,18.769,0,0,1,5.362,13.274,19.121,19.121,0,0,1-18.934,18.926,18.135,18.135,0,0,1-5.32-.814,21.083,21.083,0,0,0,1.032-1.846,31.1,31.1,0,0,0,1.478-4.733q.226-.96.671-2.591a4.786,4.786,0,0,0,1.774,1.629,7.737,7.737,0,0,0,7.022-.3,11.669,11.669,0,0,0,5.323-6.875,13.977,13.977,0,0,0-.334-9.057,10.672,10.672,0,0,0-5.951-6.027,16.44,16.44,0,0,0-10.5.333,11.8,11.8,0,0,0-7.1,6.469,15.056,15.056,0,0,0-.629,3.366,15.791,15.791,0,0,0,.11,3.253,6.4,6.4,0,0,0,1.11,2.847,5.675,5.675,0,0,0,2.363,1.922.624.624,0,0,0,.594,0c.2-.1.392-.49.587-1.181a3.6,3.6,0,0,0,.224-1.4c-.047-.1-.146-.273-.293-.519a7.205,7.205,0,0,1-1.034-5.285,9.281,9.281,0,0,1,2.292-4.693,10.273,10.273,0,0,1,6.394-2.664,8.447,8.447,0,0,1,6.246,2,7.983,7.983,0,0,1,1.81,3.918,11.963,11.963,0,0,1,0,4.4,13.258,13.258,0,0,1-1.44,3.958q-1.852,2.884-4.365,2.957a3.271,3.271,0,0,1-2.4-1.147,2.576,2.576,0,0,1-.553-2.477q.148-.812.889-3.18a16.954,16.954,0,0,0,.812-3.547q-.221-2.811-2.587-2.886a3.523,3.523,0,0,0-2.738,1.663,6.648,6.648,0,0,0-.965,3.29,8.762,8.762,0,0,0,.668,2.957q-.81,3.327-1.257,5.322c-.1.344-.37,1.406-.814,3.18a23.632,23.632,0,0,0-.739,4.067v2.072a19.491,19.491,0,0,1-8.278-7.061A18.309,18.309,0,0,1,4264.124,1231.55Z\" transform=\"translate(-4264.124 -1212.619)\"\/>\n            <\/svg>\n        <\/div>\n        <\/a><a href=\"https:\/\/ihg.bossdesign.com\/fr\/produit\/kruze\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_24636\" data-quantity=\"1\" class=\"button product_type_variable\" data-product_id=\"24636\" data-product_sku=\"\" aria-label=\"S\u00e9lectionner les options pour &ldquo;Kruze&rdquo;\" rel=\"nofollow\">Lire la suite<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_24636\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n        <a class=\"l-product-slide__link\" href=\"https:\/\/ihg.bossdesign.com\/fr\/produit\/kruze\"><\/a>\n    <\/div>\n<\/div><div >\n    <div\n            class=\"l-product-slide js-product-slides__slide\"\n            data-url=\"https:\/\/ihg.bossdesign.com\/fr\/produit\/manta\"\n            data-media=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/06\/31152823\/Boss-Design-Manta-1-scaled.jpg\"\n            data-description=\"Manta\"\n            aria-expanded=\"false\">\n        \n<div data-item_id=\"16709\" data-action=\"alg-wc-wl-toggle\" class=\"alg-wc-wl-btn add alg-wc-wl-thumb-btn alg-wc-wl-thumb-btn-abs alg-wc-wl-thumb-btn-loop\">\n\t<div class=\"alg-wc-wl-view-state alg-wc-wl-view-state-add\">\n\t\t<i class=\"l-product-slide__wishlist l-product-slide__wishlist--add\" aria-hidden=\"true\"><\/i>\n\t<\/div>\n\t<div class=\"alg-wc-wl-view-state alg-wc-wl-view-state-remove\">\n\t\t<i class=\"l-product-slide__wishlist l-product-slide__wishlist--remove\" aria-hidden=\"true\"><\/i>\n\t<\/div>\n\t<\/div><a href=\"https:\/\/ihg.bossdesign.com\/fr\/projects-fr\/corporate-fr\/financial-institution\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <div class=\"l-product-slide__image\">\n            <img decoding=\"async\" src=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/06\/31152823\/Boss-Design-Manta-1-scaled.jpg\" alt=\"Manta\" \/>\n        <\/div>\n        <div class=\"l-product-slide__info js-product-slides__slide-info\">\n            <div class=\"l-product-slide__info-inner\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/06\/31152823\/Boss-Design-Manta-1-scaled-300x225.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Manta\" srcset=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/06\/31152823\/Boss-Design-Manta-1-scaled-300x225.jpg 300w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/06\/31152823\/Boss-Design-Manta-1-scaled-600x450.jpg 600w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/06\/31152823\/Boss-Design-Manta-1-1024x768.jpg 1024w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/06\/31152823\/Boss-Design-Manta-1-768x576.jpg 768w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/06\/31152823\/Boss-Design-Manta-1-1536x1152.jpg 1536w, https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/06\/31152823\/Boss-Design-Manta-1-2048x1536.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>                <h5>\n                    Manta                <\/h5>\n                \n                <div\n                        hidden=\"hidden\"\n                        class=\"l-product-slide__call-to-action js-product-slides__call-to-action\">\n                    <p>\n                        <a href=\"https:\/\/ihg.bossdesign.com\/fr\/produit\/manta\">View product<\/a>\n                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"25.052\" height=\"18.745\" viewBox=\"0 0 25.052 18.745\">\n                            <g id=\"Group_157\" data-name=\"Group 157\" transform=\"translate(0 0.354)\">\n                                <g id=\"Group_75\" data-name=\"Group 75\" transform=\"translate(0 0)\">\n                                    <g id=\"Group_74\" data-name=\"Group 74\">\n                                        <line id=\"Line_40\" data-name=\"Line 40\" x2=\"24.552\" transform=\"translate(0 9.019)\" fill=\"none\" stroke=\"#000\" stroke-linejoin=\"round\" stroke-width=\"1\"\/>\n                                        <path id=\"Path_41\" data-name=\"Path 41\" d=\"M4596.461,1377.324l9.019,9.019-9.019,9.019\" transform=\"translate(-4580.928 -1377.324)\" fill=\"none\" stroke=\"#000\" stroke-linejoin=\"round\" stroke-width=\"1\"\/>\n                                    <\/g>\n                                <\/g>\n                            <\/g>\n                        <\/svg>\n                    <\/p>\n                <\/div>\n            <\/div>\n        <\/div>\n        <div hidden=\"hidden\"\n             class=\"l-product-slide__pin js-product-slides__slide-pin\">\n            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"37.863\" height=\"37.857\" viewBox=\"0 0 37.863 37.857\">\n                <path id=\"Path_53\" data-name=\"Path 53\" d=\"M4264.124,1231.55a18.982,18.982,0,0,1,32.5-13.274,18.769,18.769,0,0,1,5.362,13.274,19.121,19.121,0,0,1-18.934,18.926,18.135,18.135,0,0,1-5.32-.814,21.083,21.083,0,0,0,1.032-1.846,31.1,31.1,0,0,0,1.478-4.733q.226-.96.671-2.591a4.786,4.786,0,0,0,1.774,1.629,7.737,7.737,0,0,0,7.022-.3,11.669,11.669,0,0,0,5.323-6.875,13.977,13.977,0,0,0-.334-9.057,10.672,10.672,0,0,0-5.951-6.027,16.44,16.44,0,0,0-10.5.333,11.8,11.8,0,0,0-7.1,6.469,15.056,15.056,0,0,0-.629,3.366,15.791,15.791,0,0,0,.11,3.253,6.4,6.4,0,0,0,1.11,2.847,5.675,5.675,0,0,0,2.363,1.922.624.624,0,0,0,.594,0c.2-.1.392-.49.587-1.181a3.6,3.6,0,0,0,.224-1.4c-.047-.1-.146-.273-.293-.519a7.205,7.205,0,0,1-1.034-5.285,9.281,9.281,0,0,1,2.292-4.693,10.273,10.273,0,0,1,6.394-2.664,8.447,8.447,0,0,1,6.246,2,7.983,7.983,0,0,1,1.81,3.918,11.963,11.963,0,0,1,0,4.4,13.258,13.258,0,0,1-1.44,3.958q-1.852,2.884-4.365,2.957a3.271,3.271,0,0,1-2.4-1.147,2.576,2.576,0,0,1-.553-2.477q.148-.812.889-3.18a16.954,16.954,0,0,0,.812-3.547q-.221-2.811-2.587-2.886a3.523,3.523,0,0,0-2.738,1.663,6.648,6.648,0,0,0-.965,3.29,8.762,8.762,0,0,0,.668,2.957q-.81,3.327-1.257,5.322c-.1.344-.37,1.406-.814,3.18a23.632,23.632,0,0,0-.739,4.067v2.072a19.491,19.491,0,0,1-8.278-7.061A18.309,18.309,0,0,1,4264.124,1231.55Z\" transform=\"translate(-4264.124 -1212.619)\"\/>\n            <\/svg>\n        <\/div>\n        <\/a><a href=\"https:\/\/ihg.bossdesign.com\/fr\/produit\/manta\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_16709\" data-quantity=\"1\" class=\"button product_type_variable\" data-product_id=\"16709\" data-product_sku=\"\" aria-label=\"S\u00e9lectionner les options pour &ldquo;Manta&rdquo;\" rel=\"nofollow\">Lire la suite<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_16709\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n        <a class=\"l-product-slide__link\" href=\"https:\/\/ihg.bossdesign.com\/fr\/produit\/manta\"><\/a>\n    <\/div>\n<\/div>    <\/div>\n    <div class=\"c-carousel__pagination js-carousel__pagination\">\n    <span class=\"js-carousel__pagination--current\">1<\/span>\/<span class=\"js-carousel__pagination--total\">3<\/span>\n<\/div>\n<ul class=\"c-carousel__controls js-carousel__controls\">\n    <li class=\"c-carousel__control c-carousel-controls c-carousel-controls__previous js-carousel__control--previous\">\n        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"9.849\" height=\"17.699\" viewBox=\"0 0 9.849 17.699\">\n    <path id=\"previous-arrow\" data-name=\"back-chevron\" d=\"M0,16.992,8.789,8.2.585,0\" transform=\"translate(9.496 17.346) rotate(180)\" fill=\"none\" stroke=\"#000\" stroke-miterlimit=\"10\" stroke-width=\"1\"\/>\n<\/svg>        <span>Previous<\/span>\n    <\/li>\n    <li class=\"c-carousel__control c-carousel-controls c-carousel-controls__next js-carousel__control--next\">\n        <span>Next<\/span>\n        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"9.849\" height=\"17.699\" viewBox=\"0 0 9.849 17.699\">\n    <path id=\"next-arrow\" data-name=\"forward-chevron\" d=\"M4777.469,1010.609l8.789-8.789-8.2-8.2\" transform=\"translate(-4777.115 -993.263)\" fill=\"none\" stroke=\"#000\" stroke-miterlimit=\"10\" stroke-width=\"1\"\/>\n<\/svg>    <\/li>\n<\/ul><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Oman, Middle East Bringing luxury and elegance to the workplace, this high profile global financial institution specified the Boss Design classic, Kruze, to sit around bespoke boardroom tables. Combining traditional and antique artworks, with a modern finish spec on the furniture, brings a level of sophistication and opulence not usually associated within the workplace arena. [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":15674,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[256],"tags":[],"class_list":["post-28307","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-corporate-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Financial Institution - Boss Design x IHG<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ihg.bossdesign.com\/fr\/projects-fr\/corporate-fr\/financial-institution\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Financial Institution - Boss Design x IHG\" \/>\n<meta property=\"og:description\" content=\"Oman, Middle East Bringing luxury and elegance to the workplace, this high profile global financial institution specified the Boss Design classic, Kruze, to sit around bespoke boardroom tables. Combining traditional and antique artworks, with a modern finish spec on the furniture, brings a level of sophistication and opulence not usually associated within the workplace arena. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ihg.bossdesign.com\/fr\/projects-fr\/corporate-fr\/financial-institution\" \/>\n<meta property=\"og:site_name\" content=\"Boss Design x IHG\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-20T10:24:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-20T10:24:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/26140222\/london_financial_institution_2-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jon Earp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jon Earp\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ihg.bossdesign.com\\\/fr\\\/projects-fr\\\/corporate-fr\\\/financial-institution#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ihg.bossdesign.com\\\/fr\\\/projects-fr\\\/corporate-fr\\\/financial-institution\"},\"author\":{\"name\":\"Jon Earp\",\"@id\":\"https:\\\/\\\/ihg.bossdesign.com\\\/fr#\\\/schema\\\/person\\\/5a0f8d321ec00940dff3e209336af130\"},\"headline\":\"Financial Institution\",\"datePublished\":\"2022-06-20T10:24:54+00:00\",\"dateModified\":\"2022-06-20T10:24:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ihg.bossdesign.com\\\/fr\\\/projects-fr\\\/corporate-fr\\\/financial-institution\"},\"wordCount\":109,\"publisher\":{\"@id\":\"https:\\\/\\\/ihg.bossdesign.com\\\/fr#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/ihg.bossdesign.com\\\/fr\\\/projects-fr\\\/corporate-fr\\\/financial-institution#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/boss-design-assets.s3.eu-west-2.amazonaws.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/26140222\\\/london_financial_institution_2-1.jpg\",\"articleSection\":[\"Corporate\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ihg.bossdesign.com\\\/fr\\\/projects-fr\\\/corporate-fr\\\/financial-institution\",\"url\":\"https:\\\/\\\/ihg.bossdesign.com\\\/fr\\\/projects-fr\\\/corporate-fr\\\/financial-institution\",\"name\":\"Financial Institution - Boss Design x IHG\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ihg.bossdesign.com\\\/fr#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ihg.bossdesign.com\\\/fr\\\/projects-fr\\\/corporate-fr\\\/financial-institution#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ihg.bossdesign.com\\\/fr\\\/projects-fr\\\/corporate-fr\\\/financial-institution#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/boss-design-assets.s3.eu-west-2.amazonaws.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/26140222\\\/london_financial_institution_2-1.jpg\",\"datePublished\":\"2022-06-20T10:24:54+00:00\",\"dateModified\":\"2022-06-20T10:24:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ihg.bossdesign.com\\\/fr\\\/projects-fr\\\/corporate-fr\\\/financial-institution#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ihg.bossdesign.com\\\/fr\\\/projects-fr\\\/corporate-fr\\\/financial-institution\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/ihg.bossdesign.com\\\/fr\\\/projects-fr\\\/corporate-fr\\\/financial-institution#primaryimage\",\"url\":\"https:\\\/\\\/boss-design-assets.s3.eu-west-2.amazonaws.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/26140222\\\/london_financial_institution_2-1.jpg\",\"contentUrl\":\"https:\\\/\\\/boss-design-assets.s3.eu-west-2.amazonaws.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/26140222\\\/london_financial_institution_2-1.jpg\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ihg.bossdesign.com\\\/fr\\\/projects-fr\\\/corporate-fr\\\/financial-institution#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ihg.bossdesign.com\\\/fr\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Financial Institution\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ihg.bossdesign.com\\\/fr#website\",\"url\":\"https:\\\/\\\/ihg.bossdesign.com\\\/fr\",\"name\":\"Boss Design x IHG\",\"description\":\"Boss Design - leading furniture designer and manufacturer\",\"publisher\":{\"@id\":\"https:\\\/\\\/ihg.bossdesign.com\\\/fr#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ihg.bossdesign.com\\\/fr?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ihg.bossdesign.com\\\/fr#organization\",\"name\":\"Boss Design x IHG\",\"url\":\"https:\\\/\\\/ihg.bossdesign.com\\\/fr\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/ihg.bossdesign.com\\\/fr#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/boss-design-assets.s3.eu-west-2.amazonaws.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/29105425\\\/Boss-x-IHG-Logo-Header3.png\",\"contentUrl\":\"https:\\\/\\\/boss-design-assets.s3.eu-west-2.amazonaws.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/29105425\\\/Boss-x-IHG-Logo-Header3.png\",\"width\":900,\"height\":231,\"caption\":\"Boss Design x IHG\"},\"image\":{\"@id\":\"https:\\\/\\\/ihg.bossdesign.com\\\/fr#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ihg.bossdesign.com\\\/fr#\\\/schema\\\/person\\\/5a0f8d321ec00940dff3e209336af130\",\"name\":\"Jon Earp\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ed117e4188ce729afcaacf65e1e3dddb03cffd1f6ebd0394ae8203f9aa98ac1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ed117e4188ce729afcaacf65e1e3dddb03cffd1f6ebd0394ae8203f9aa98ac1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ed117e4188ce729afcaacf65e1e3dddb03cffd1f6ebd0394ae8203f9aa98ac1?s=96&d=mm&r=g\",\"caption\":\"Jon Earp\"},\"url\":\"https:\\\/\\\/ihg.bossdesign.com\\\/fr\\\/author\\\/jearpbossdesign-com\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Financial Institution - Boss Design x IHG","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ihg.bossdesign.com\/fr\/projects-fr\/corporate-fr\/financial-institution","og_locale":"fr_FR","og_type":"article","og_title":"Financial Institution - Boss Design x IHG","og_description":"Oman, Middle East Bringing luxury and elegance to the workplace, this high profile global financial institution specified the Boss Design classic, Kruze, to sit around bespoke boardroom tables. Combining traditional and antique artworks, with a modern finish spec on the furniture, brings a level of sophistication and opulence not usually associated within the workplace arena. [&hellip;]","og_url":"https:\/\/ihg.bossdesign.com\/fr\/projects-fr\/corporate-fr\/financial-institution","og_site_name":"Boss Design x IHG","article_published_time":"2022-06-20T10:24:54+00:00","article_modified_time":"2022-06-20T10:24:55+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/26140222\/london_financial_institution_2-1.jpg","type":"image\/jpeg"}],"author":"Jon Earp","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Jon Earp","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ihg.bossdesign.com\/fr\/projects-fr\/corporate-fr\/financial-institution#article","isPartOf":{"@id":"https:\/\/ihg.bossdesign.com\/fr\/projects-fr\/corporate-fr\/financial-institution"},"author":{"name":"Jon Earp","@id":"https:\/\/ihg.bossdesign.com\/fr#\/schema\/person\/5a0f8d321ec00940dff3e209336af130"},"headline":"Financial Institution","datePublished":"2022-06-20T10:24:54+00:00","dateModified":"2022-06-20T10:24:55+00:00","mainEntityOfPage":{"@id":"https:\/\/ihg.bossdesign.com\/fr\/projects-fr\/corporate-fr\/financial-institution"},"wordCount":109,"publisher":{"@id":"https:\/\/ihg.bossdesign.com\/fr#organization"},"image":{"@id":"https:\/\/ihg.bossdesign.com\/fr\/projects-fr\/corporate-fr\/financial-institution#primaryimage"},"thumbnailUrl":"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/26140222\/london_financial_institution_2-1.jpg","articleSection":["Corporate"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/ihg.bossdesign.com\/fr\/projects-fr\/corporate-fr\/financial-institution","url":"https:\/\/ihg.bossdesign.com\/fr\/projects-fr\/corporate-fr\/financial-institution","name":"Financial Institution - Boss Design x IHG","isPartOf":{"@id":"https:\/\/ihg.bossdesign.com\/fr#website"},"primaryImageOfPage":{"@id":"https:\/\/ihg.bossdesign.com\/fr\/projects-fr\/corporate-fr\/financial-institution#primaryimage"},"image":{"@id":"https:\/\/ihg.bossdesign.com\/fr\/projects-fr\/corporate-fr\/financial-institution#primaryimage"},"thumbnailUrl":"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/26140222\/london_financial_institution_2-1.jpg","datePublished":"2022-06-20T10:24:54+00:00","dateModified":"2022-06-20T10:24:55+00:00","breadcrumb":{"@id":"https:\/\/ihg.bossdesign.com\/fr\/projects-fr\/corporate-fr\/financial-institution#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ihg.bossdesign.com\/fr\/projects-fr\/corporate-fr\/financial-institution"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/ihg.bossdesign.com\/fr\/projects-fr\/corporate-fr\/financial-institution#primaryimage","url":"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/26140222\/london_financial_institution_2-1.jpg","contentUrl":"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/10\/26140222\/london_financial_institution_2-1.jpg","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/ihg.bossdesign.com\/fr\/projects-fr\/corporate-fr\/financial-institution#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ihg.bossdesign.com\/fr"},{"@type":"ListItem","position":2,"name":"Financial Institution"}]},{"@type":"WebSite","@id":"https:\/\/ihg.bossdesign.com\/fr#website","url":"https:\/\/ihg.bossdesign.com\/fr","name":"Boss Design x IHG","description":"Boss Design - leading furniture designer and manufacturer","publisher":{"@id":"https:\/\/ihg.bossdesign.com\/fr#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ihg.bossdesign.com\/fr?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/ihg.bossdesign.com\/fr#organization","name":"Boss Design x IHG","url":"https:\/\/ihg.bossdesign.com\/fr","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/ihg.bossdesign.com\/fr#\/schema\/logo\/image\/","url":"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/04\/29105425\/Boss-x-IHG-Logo-Header3.png","contentUrl":"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/04\/29105425\/Boss-x-IHG-Logo-Header3.png","width":900,"height":231,"caption":"Boss Design x IHG"},"image":{"@id":"https:\/\/ihg.bossdesign.com\/fr#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ihg.bossdesign.com\/fr#\/schema\/person\/5a0f8d321ec00940dff3e209336af130","name":"Jon Earp","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/3ed117e4188ce729afcaacf65e1e3dddb03cffd1f6ebd0394ae8203f9aa98ac1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3ed117e4188ce729afcaacf65e1e3dddb03cffd1f6ebd0394ae8203f9aa98ac1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3ed117e4188ce729afcaacf65e1e3dddb03cffd1f6ebd0394ae8203f9aa98ac1?s=96&d=mm&r=g","caption":"Jon Earp"},"url":"https:\/\/ihg.bossdesign.com\/fr\/author\/jearpbossdesign-com"}]}},"_links":{"self":[{"href":"https:\/\/ihg.bossdesign.com\/fr\/wp-json\/wp\/v2\/posts\/28307","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ihg.bossdesign.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ihg.bossdesign.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ihg.bossdesign.com\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/ihg.bossdesign.com\/fr\/wp-json\/wp\/v2\/comments?post=28307"}],"version-history":[{"count":0,"href":"https:\/\/ihg.bossdesign.com\/fr\/wp-json\/wp\/v2\/posts\/28307\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ihg.bossdesign.com\/fr\/wp-json\/wp\/v2\/media\/15674"}],"wp:attachment":[{"href":"https:\/\/ihg.bossdesign.com\/fr\/wp-json\/wp\/v2\/media?parent=28307"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ihg.bossdesign.com\/fr\/wp-json\/wp\/v2\/categories?post=28307"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ihg.bossdesign.com\/fr\/wp-json\/wp\/v2\/tags?post=28307"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}