{"id":18134,"date":"2021-11-05T11:45:00","date_gmt":"2021-11-05T11:45:00","guid":{"rendered":"https:\/\/boss2.startlingideas.com\/cookie-policy"},"modified":"2021-12-20T23:39:53","modified_gmt":"2021-12-20T23:39:53","slug":"cookie-policy","status":"publish","type":"page","link":"https:\/\/ihg.bossdesign.com\/fr\/cookie-policy","title":{"rendered":"Cookie Policy"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Notre site Web utilise des cookies, comme presque tous les sites Web, pour vous offrir la meilleure exp\u00e9rience possible. Les cookies sont de petits fichiers texte qui sont plac\u00e9s sur votre ordinateur ou votre t\u00e9l\u00e9phone portable lorsque vous naviguez sur des sites Internet. Nos cookies permettent de\u00a0:<\/p>\n\n<ul class=\"wp-block-list\"><li>Faire fonctionner notre site Web comme vous vous y attendez<\/li><li>M\u00e9moriser vos param\u00e8tres pendant et entre les visites<\/li><li>Am\u00e9liorer la vitesse\/la s\u00e9curit\u00e9 du site<\/li><li>Pouvoir partager des pages avec des r\u00e9seaux sociaux comme Facebook<\/li><li>Am\u00e9liorer continuellement notre site Web pour vous<\/li><li>Rendre notre marketing plus efficace (en fin de compte, nous aider \u00e0 offrir le<br \/>service que nous proposons au prix que nous pratiquons)<\/li><\/ul>\n\n<p class=\"wp-block-paragraph\">Nous n&rsquo;utilisons pas de cookies pour\u00a0:<\/p>\n\n<ul class=\"wp-block-list\"><li>Recueillir toute information personnellement identifiable (sans votre consentement<br \/>formel)<\/li><li>Collecter des informations sensibles (sans votre consentement formel)<\/li><li>Transmettre des donn\u00e9es aux r\u00e9seaux publicitaires<\/li><li>Transmettre des donn\u00e9es personnellement identifiables \u00e0 des tiers<\/li><li>Payer des commissions de vente<\/li><\/ul>\n\n<p class=\"wp-block-paragraph\">Vous pouvez en savoir plus sur tous les cookies que nous utilisons ci-dessous<br \/><\/p>\n\n<h4 class=\"wp-block-heading\"><strong>Nous autoriser \u00e0 utiliser des cookies<\/strong><\/h4>\n\n<p class=\"wp-block-paragraph\">Si les param\u00e8tres du logiciel que vous utilisez pour afficher ce site Web (votre navigateur) sont r\u00e9gl\u00e9s pour accepter les cookies, nous consid\u00e9rons cela, ainsi que votre utilisation continue de notre site Web, comme un accord de votre part. Si vous souhaitez supprimer ou ne pas utiliser les cookies de notre site, vous pouvez apprendre comment proc\u00e9der ci-dessous, mais cela signifiera probablement que notre site ne fonctionnera pas comme vous le souhaiteriez.<br \/><\/p>\n\n<h4 class=\"wp-block-heading\"><strong>En savoir plus sur nos cookies<\/strong><\/h4>\n\n<p class=\"wp-block-paragraph\">Cookies de fonction du site Web<br \/><em>Nos propres cookies Nous utilisons des cookies pour faire fonctionner notre site Web, notamment pour\u00a0:<\/em><\/p>\n\n<ul class=\"wp-block-list\"><li>M\u00e9moriser vos param\u00e8tres de recherche<\/li><\/ul>\n\n<p class=\"wp-block-paragraph\">Le seul moyen pour emp\u00eacher la configuration de ces cookies est de ne pas utiliser notre<br \/>site.<br \/><\/p>\n\n<h4 class=\"wp-block-heading\"><strong>Cookies de sites Web sociaux<\/strong><\/h4>\n\n<p class=\"wp-block-paragraph\">Ainsi, vous pouvez facilement aimer ou partager notre contenu sur Facebook et Twitter, nous avons inclus des boutons de partage sur notre site. Les cookies sont d\u00e9finis par\u00a0:<\/p>\n\n<ul class=\"wp-block-list\"><li>AddThis &#8211; La politique de confidentialit\u00e9 nous fournit de nombreux boutons de partage dans<br \/>un paquet bien emball\u00e9<\/li><\/ul>\n\n<p class=\"wp-block-paragraph\">Les implications sur la vie priv\u00e9e \u00e0 ce sujet varieront d&rsquo;un r\u00e9seau social \u00e0 l&rsquo;autre et d\u00e9pendront des param\u00e8tres de confidentialit\u00e9 que vous avez choisis sur ces r\u00e9seaux.<br \/><\/p>\n\n<h4 class=\"wp-block-heading\"><strong>Cookies de statistiques de visiteurs anonymes<\/strong><\/h4>\n\n<p class=\"wp-block-paragraph\">Nous utilisons des cookies pour compiler des statistiques sur les visiteurs, telles que le nombre de personnes qui ont visit\u00e9 notre site Web, le type de technologie qu&rsquo;elles utilisent (par exemple, Mac ou Windows, ce qui permet d&rsquo;identifier quand notre site ne fonctionne pas correctement pour des technologies particuli\u00e8res), la dur\u00e9e pass\u00e9e sur le site, les pages consult\u00e9es, etc. Cela nous aide \u00e0 am\u00e9liorer continuellement notre site Web. Ces programmes dits d&rsquo;analyse nous indiquent \u00e9galement, sur une base anonyme, comment les personnes ont acc\u00e9d\u00e9 \u00e0 ce site (par exemple \u00e0 partir d&rsquo;un moteur de recherche) et s&rsquo;ils l&rsquo;ont d\u00e9j\u00e0 consult\u00e9 pr\u00e9c\u00e9demment. Cela nous aide \u00e0 savoir s&rsquo;il faut investir plus d&rsquo;argent dans le d\u00e9veloppement de nos services plut\u00f4t que dans les d\u00e9penses marketing. Nous utilisons\u00a0: Google Analytics.<br \/><\/p>\n\n<h4 class=\"wp-block-heading\">D\u00e9sactiver les cookies<\/h4>\n\n<p class=\"wp-block-paragraph\">Vous pouvez g\u00e9n\u00e9ralement d\u00e9sactiver les cookies en ajustant les param\u00e8tres de votre navigateur pour l&#8217;emp\u00eacher d&rsquo;accepter les cookies (D\u00e9couvrez comment ici). Cependant, cela limitera probablement la fonctionnalit\u00e9 de nos sites Web et d&rsquo;une grande partie des sites Web du monde, car les cookies font partie int\u00e9grante de la plupart des sites Web modernes. Il se peut que vos pr\u00e9occupations concernant les cookies soient li\u00e9es \u00e0 ce que l&rsquo;on appelle les \u00ab\u00a0logiciels espions\u00a0\u00bb. Plut\u00f4t que de d\u00e9sactiver les cookies dans votre navigateur, vous constaterez peut-\u00eatre qu&rsquo;un logiciel anti-espion atteint le m\u00eame objectif en supprimant automatiquement les cookies consid\u00e9r\u00e9s comme invasifs. En savoir plus sur la gestion des cookies avec un logiciel anti-espion.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Notre site Web utilise des cookies, comme presque tous les sites Web, pour vous offrir la meilleure exp\u00e9rience possible. Les cookies sont de petits fichiers texte qui sont plac\u00e9s sur votre ordinateur ou votre t\u00e9l\u00e9phone portable lorsque vous naviguez sur des sites Internet. Nos cookies permettent de\u00a0: Faire fonctionner notre site Web comme vous vous [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-18134","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cookie Policy - Boss Design x IHG<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ihg.bossdesign.com\/fr\/cookie-policy\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cookie Policy - Boss Design x IHG\" \/>\n<meta property=\"og:description\" content=\"Notre site Web utilise des cookies, comme presque tous les sites Web, pour vous offrir la meilleure exp\u00e9rience possible. Les cookies sont de petits fichiers texte qui sont plac\u00e9s sur votre ordinateur ou votre t\u00e9l\u00e9phone portable lorsque vous naviguez sur des sites Internet. Nos cookies permettent de\u00a0: Faire fonctionner notre site Web comme vous vous [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ihg.bossdesign.com\/fr\/cookie-policy\" \/>\n<meta property=\"og:site_name\" content=\"Boss Design x IHG\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-20T23:39:53+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ihg.bossdesign.com\\\/fr\\\/cookie-policy\",\"url\":\"https:\\\/\\\/ihg.bossdesign.com\\\/fr\\\/cookie-policy\",\"name\":\"Cookie Policy - Boss Design x IHG\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ihg.bossdesign.com\\\/fr#website\"},\"datePublished\":\"2021-11-05T11:45:00+00:00\",\"dateModified\":\"2021-12-20T23:39:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ihg.bossdesign.com\\\/fr\\\/cookie-policy#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ihg.bossdesign.com\\\/fr\\\/cookie-policy\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ihg.bossdesign.com\\\/fr\\\/cookie-policy#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ihg.bossdesign.com\\\/fr\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cookie Policy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ihg.bossdesign.com\\\/fr#website\",\"url\":\"https:\\\/\\\/ihg.bossdesign.com\\\/fr\",\"name\":\"Boss Design x IHG\",\"description\":\"Boss Design - leading furniture designer and manufacturer\",\"publisher\":{\"@id\":\"https:\\\/\\\/ihg.bossdesign.com\\\/fr#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ihg.bossdesign.com\\\/fr?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ihg.bossdesign.com\\\/fr#organization\",\"name\":\"Boss Design x IHG\",\"url\":\"https:\\\/\\\/ihg.bossdesign.com\\\/fr\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/ihg.bossdesign.com\\\/fr#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/boss-design-assets.s3.eu-west-2.amazonaws.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/29105425\\\/Boss-x-IHG-Logo-Header3.png\",\"contentUrl\":\"https:\\\/\\\/boss-design-assets.s3.eu-west-2.amazonaws.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/29105425\\\/Boss-x-IHG-Logo-Header3.png\",\"width\":900,\"height\":231,\"caption\":\"Boss Design x IHG\"},\"image\":{\"@id\":\"https:\\\/\\\/ihg.bossdesign.com\\\/fr#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cookie Policy - Boss Design x IHG","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ihg.bossdesign.com\/fr\/cookie-policy","og_locale":"fr_FR","og_type":"article","og_title":"Cookie Policy - Boss Design x IHG","og_description":"Notre site Web utilise des cookies, comme presque tous les sites Web, pour vous offrir la meilleure exp\u00e9rience possible. Les cookies sont de petits fichiers texte qui sont plac\u00e9s sur votre ordinateur ou votre t\u00e9l\u00e9phone portable lorsque vous naviguez sur des sites Internet. Nos cookies permettent de\u00a0: Faire fonctionner notre site Web comme vous vous [&hellip;]","og_url":"https:\/\/ihg.bossdesign.com\/fr\/cookie-policy","og_site_name":"Boss Design x IHG","article_modified_time":"2021-12-20T23:39:53+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ihg.bossdesign.com\/fr\/cookie-policy","url":"https:\/\/ihg.bossdesign.com\/fr\/cookie-policy","name":"Cookie Policy - Boss Design x IHG","isPartOf":{"@id":"https:\/\/ihg.bossdesign.com\/fr#website"},"datePublished":"2021-11-05T11:45:00+00:00","dateModified":"2021-12-20T23:39:53+00:00","breadcrumb":{"@id":"https:\/\/ihg.bossdesign.com\/fr\/cookie-policy#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ihg.bossdesign.com\/fr\/cookie-policy"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ihg.bossdesign.com\/fr\/cookie-policy#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ihg.bossdesign.com\/fr"},{"@type":"ListItem","position":2,"name":"Cookie Policy"}]},{"@type":"WebSite","@id":"https:\/\/ihg.bossdesign.com\/fr#website","url":"https:\/\/ihg.bossdesign.com\/fr","name":"Boss Design x IHG","description":"Boss Design - leading furniture designer and manufacturer","publisher":{"@id":"https:\/\/ihg.bossdesign.com\/fr#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ihg.bossdesign.com\/fr?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/ihg.bossdesign.com\/fr#organization","name":"Boss Design x IHG","url":"https:\/\/ihg.bossdesign.com\/fr","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/ihg.bossdesign.com\/fr#\/schema\/logo\/image\/","url":"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/04\/29105425\/Boss-x-IHG-Logo-Header3.png","contentUrl":"https:\/\/boss-design-assets.s3.eu-west-2.amazonaws.com\/wp-content\/uploads\/2021\/04\/29105425\/Boss-x-IHG-Logo-Header3.png","width":900,"height":231,"caption":"Boss Design x IHG"},"image":{"@id":"https:\/\/ihg.bossdesign.com\/fr#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/ihg.bossdesign.com\/fr\/wp-json\/wp\/v2\/pages\/18134","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ihg.bossdesign.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ihg.bossdesign.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ihg.bossdesign.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ihg.bossdesign.com\/fr\/wp-json\/wp\/v2\/comments?post=18134"}],"version-history":[{"count":0,"href":"https:\/\/ihg.bossdesign.com\/fr\/wp-json\/wp\/v2\/pages\/18134\/revisions"}],"wp:attachment":[{"href":"https:\/\/ihg.bossdesign.com\/fr\/wp-json\/wp\/v2\/media?parent=18134"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}